{"id":126318,"date":"2019-07-11T14:30:40","date_gmt":"2019-07-11T14:30:40","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126318"},"modified":"2019-07-11T14:30:40","modified_gmt":"2019-07-11T14:30:40","slug":"la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/","title":{"rendered":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-19556\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Wiesbaden (Alemania), 11 jul (dpa) &#8211; La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden.<\/p>\n<p>Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo hab\u00eda sido del 1,4 por ciento. En comparaci\u00f3n con el mes anterior, los precios subieron un 0,3 por ciento en junio.<\/p>\n<p>Una de las principales causas del aumento de la inflaci\u00f3n, de acuerdo con las estad\u00edsticas de Wiesbaden, fue el aumento de los precios de los paquetes tur\u00edsticos, que subieron bruscamente un 6,1 por ciento en junio, en relaci\u00f3n al mismo mes del a\u00f1o precedente.<\/p>\n<p>Sin embargo cabe mencionar que las fiestas de Pentecost\u00e9s, populares entre los vacacionistas, cayeron este a\u00f1o en junio, mientras que en 2018 fueron en mayo, lo que tuvo incidencia en las cifras.<\/p>\n<p>Por otro lado, el aumento de los precios de la energ\u00eda se debilit\u00f3 y se ubic\u00f3 en 2,5 por ciento. No obstante, los servicios de calefacci\u00f3n, el gas natural y la electricidad registraron precios m\u00e1s altos que hace un a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wiesbaden (Alemania), 11 jul (dpa) &#8211; La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo<\/p>\n","protected":false},"author":1,"featured_media":119391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126318","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-11T14:30:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-11T14:30:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#listItem\",\"name\":\"La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio de 2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#listItem\",\"position\":3,\"name\":\"La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio de 2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#newsarticle\",\"name\":\"La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio de 2019 | Cand\\u00e1s 365\",\"headline\":\"La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio de 2019\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/money-3481699_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2019-07-11T14:30:40+02:00\",\"dateModified\":\"2019-07-11T14:30:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 11, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/\",\"name\":\"La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio de 2019 | Cand\\u00e1s 365\",\"description\":\"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\\u00f3n en Alemania se aceler\\u00f3 ligeramente en junio, confirm\\u00f3 hoy la Oficina Federal de Estad\\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\\u00f1o pasado, seg\\u00fan los datos oficiales. En mayo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/money-3481699_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\\\/#mainImage\"},\"datePublished\":\"2019-07-11T14:30:40+02:00\",\"dateModified\":\"2019-07-11T14:30:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365","description":"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo","canonical_url":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#listItem","name":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#listItem","position":3,"name":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#newsarticle","name":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365","headline":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg","width":960,"height":640},"datePublished":"2019-07-11T14:30:40+02:00","dateModified":"2019-07-11T14:30:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 11, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/","name":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365","description":"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/#mainImage"},"datePublished":"2019-07-11T14:30:40+02:00","dateModified":"2019-07-11T14:30:40+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365","og:description":"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo","og:url":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2019-07-11T14:30:40+00:00","article:modified_time":"2019-07-11T14:30:40+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019 | Cand\u00e1s 365","twitter:description":"Wiesbaden (Alemania), 11 jul (dpa) - La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio, confirm\u00f3 hoy la Oficina Federal de Estad\u00edstica de Alemania en la ciudad de Wiesbaden. Los precios al consumidor se situaron un 1,6 por ciento por encima del nivel del mismo mes del a\u00f1o pasado, seg\u00fan los datos oficiales. En mayo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/money-3481699_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"126318","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 13:25:38","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:58","updated":"2026-05-24 13:25:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La inflaci\u00f3n en Alemania se aceler\u00f3 ligeramente en junio de 2019","link":"https:\/\/candas365.es\/noticias\/la-inflacion-en-alemania-se-acelero-ligeramente-en-junio-de-2019\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126318"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/119391"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}