{"id":126117,"date":"2019-07-08T17:37:43","date_gmt":"2019-07-08T17:37:43","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126117"},"modified":"2019-07-08T17:37:43","modified_gmt":"2019-07-08T17:37:43","slug":"accidente-de-trafico-en-valdes-deja-una-persona-herida","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/","title":{"rendered":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida"},"content":{"rendered":"<p style=\"font-weight: 400;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-126119\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-225x300.jpg 225w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-768x1024.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-360x480.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-696x928.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-1068x1424.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1-315x420.jpg 315w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a Cadavedo, en Vald\u00e9s.<\/p>\n<p style=\"font-weight: 400;\">Seg\u00fan los datos facilitados por el Servicio de Atenci\u00f3n M\u00e9dica Urgente (SAMU), el afectado, un var\u00f3n de 36 a\u00f1os de edad fue evacuado por el equipo m\u00e9dico de la UVI-m\u00f3vil de Jarrio al Hospital San Agust\u00edn de Avil\u00e9s. A expensas de m\u00e1s pruebas y hasta nueva valoraci\u00f3n m\u00e9dica su pron\u00f3stico es reservado.<\/p>\n<p style=\"font-weight: 400;\">El herido tuvo que ser excarcelado del interior del turismo por efectivos de Bomberos del SEPA (Servicio de Emergencias del Principado de Asturias) con base en el parque de Vald\u00e9s. Para acceder hasta el afectado los bomberos montaron un polipasto y adem\u00e1s colocaron una escalera. Tras bajar hasta el coche procedieron a abrir hueco retirando ambas puertas y le colocaron un collar\u00edn al conductor del coche al que liberaron. Posteriormente, con ayuda de los bomberos, subi\u00f3 por la escalera hasta la carretera donde le esperaba el equipo sanitario.<\/p>\n<p style=\"font-weight: 400;\">El Centro de Coordinaci\u00f3n de Emergencias del 112 Asturias recibi\u00f3 el aviso a las 15.58 horas. En la llamada se\u00f1alaban que un veh\u00edculo se hab\u00eda salido de la v\u00eda, hab\u00eda ca\u00eddo por un desnivel de unos 5-7 metros y, al menos hab\u00eda un atrapado.<\/p>\n<p style=\"font-weight: 400;\">La Sala 112 del SEPA activ\u00f3 a los bomberos del parque valdesano y pas\u00f3 el aviso al SAMU que envi\u00f3 los medios ya citados. Tambi\u00e9n inform\u00f3 a la Guardia Civil que envi\u00f3 una patrulla a la zona. A las 16.40 horas los bomberos informan que ya han liberado al herido.<\/p>\n<p style=\"font-weight: 400;\">Tras realizar tareas de seguridad, finalizada la intervenci\u00f3n retiraron para regresa a base donde llegaron al as 17.58 horas.<\/p>\n<p><b><u><span lang=\"ES\">FOTO CEDIDA POR BOMBEROS DEL SEPA<\/span><\/u><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a<\/p>\n","protected":false},"author":1,"featured_media":126119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126117","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-08T17:37:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-08T17:37:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#listItem\",\"name\":\"Accidente de tr\\u00e1fico en Vald\\u00e9s deja una persona herida\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#listItem\",\"position\":3,\"name\":\"Accidente de tr\\u00e1fico en Vald\\u00e9s deja una persona herida\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#newsarticle\",\"name\":\"Accidente de tr\\u00e1fico en Vald\\u00e9s deja una persona herida | Cand\\u00e1s 365\",\"headline\":\"Accidente de tr\\u00e1fico en Vald\\u00e9s deja una persona herida\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg\",\"width\":1200,\"height\":1600},\"datePublished\":\"2019-07-08T17:37:43+02:00\",\"dateModified\":\"2019-07-08T17:37:43+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 8, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/\",\"name\":\"Accidente de tr\\u00e1fico en Vald\\u00e9s deja una persona herida | Cand\\u00e1s 365\",\"description\":\"Seg\\u00fan la informaci\\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\\u00f3n este lunes al salirse de la v\\u00eda con el veh\\u00edculo que conduc\\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\\u00e9trico 152, en la curva de El Rib\\u00f3n, llegando a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#mainImage\",\"width\":1200,\"height\":1600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/accidente-de-trafico-en-valdes-deja-una-persona-herida\\\/#mainImage\"},\"datePublished\":\"2019-07-08T17:37:43+02:00\",\"dateModified\":\"2019-07-08T17:37:43+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365","description":"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a","canonical_url":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#listItem","name":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#listItem","position":3,"name":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#newsarticle","name":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365","headline":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg","width":1200,"height":1600},"datePublished":"2019-07-08T17:37:43+02:00","dateModified":"2019-07-08T17:37:43+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 8, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#webpage","url":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/","name":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365","description":"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg","@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#mainImage","width":1200,"height":1600},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/#mainImage"},"datePublished":"2019-07-08T17:37:43+02:00","dateModified":"2019-07-08T17:37:43+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365","og:description":"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a","og:url":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg","og:image:width":1200,"og:image:height":1600,"article:published_time":"2019-07-08T17:37:43+00:00","article:modified_time":"2019-07-08T17:37:43+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida | Cand\u00e1s 365","twitter:description":"Seg\u00fan la informaci\u00f3n suministrada por el Servicio de Emergencias del Principado de Asturias (SEPA), una persona ha resultado herida de consideraci\u00f3n este lunes al salirse de la v\u00eda con el veh\u00edculo que conduc\u00eda y volcar, cuando circulaba por la N-632, a la altura del punto kilom\u00e9trico 152, en la curva de El Rib\u00f3n, llegando a","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/ACCIDENTE-DE-TRAFICO-EN-VALDES-1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"126117","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 12:53:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:55:14","updated":"2026-05-24 12:53:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAccidente de tr\u00e1fico en Vald\u00e9s deja una persona herida\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Accidente de tr\u00e1fico en Vald\u00e9s deja una persona herida","link":"https:\/\/candas365.es\/noticias\/accidente-de-trafico-en-valdes-deja-una-persona-herida\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126117"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/126119"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}