{"id":126099,"date":"2019-07-08T10:18:30","date_gmt":"2019-07-08T10:18:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126099"},"modified":"2019-07-08T10:18:30","modified_gmt":"2019-07-08T10:18:30","slug":"risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/","title":{"rendered":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-126100\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg 512w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo aislamiento durante 1.500 a\u00f1os.<\/p>\n<p>\u200bNada m\u00e1s conocer la noticia, el ministro de Cultura y Deporte, Jos\u00e9 Guirao, ha felicitado a todos los canarios \u00abpor haber sabido conservar a lo largo de los siglos esta enorme riqueza de yacimientos arqueol\u00f3gicos en el seno de un paisaje sobrecogedor\u00bb.<\/p>\n<p>El ministro ha hecho extensivas estas felicitaciones a todos los ciudadanos \u00abporque nuestro pa\u00eds es l\u00edder mundial de declaraciones de Patrimonio Mundial. Con esta son ya 48, somos el tercer pa\u00eds del mundo, despu\u00e9s de China e Italia, en n\u00famero de declaraciones pero somos el primer pa\u00eds del mundo en diversidad de ese patrimonio\u00bb.<\/p>\n<p>Jos\u00e9 Guirao ha aprovechado la ocasi\u00f3n para se\u00f1alar que el Gobierno va a \u00abseguir trabajando para conservar, difundir y mantener para las generaciones futuras este riqu\u00edsimo patrimonio\u00bb y ha invitado a todo el mundo a que \u00abvisiten Risco Ca\u00eddo y todos los bienes reconocidos en Espa\u00f1a a lo largo de las \u00faltimas d\u00e9cadas\u00bb.<\/p>\n<p>La satisfacci\u00f3n por este nuevo reconocimiento ha sido transmitida al ministro por la delegaci\u00f3n espa\u00f1ola que ha acudido a Bak\u00fa para defender la candidatura, y que ha estado formada por el embajador delegado permanente ante la UNESCO, Juan Andr\u00e9s Perell\u00f3; el director general de Bellas Artes, Rom\u00e1n Fern\u00e1ndez-Baca; la subdirectora general de Protecci\u00f3n del Patrimonio Hist\u00f3rico, Elisa de Cabo; el director general de Patrimonio Cultural del Gobierno de Canarias, Miguel \u00c1ngel Clavijo; y el presidente del Cabildo, Antonio Morales.<\/p>\n<h3>El valor universal excepcional de las antiguas poblaciones de Canarias<\/h3>\n<p>Los yacimientos arqueol\u00f3gicos agrupados en el paisaje cultural de Risco Ca\u00eddo muestran la cultura de las antiguas poblaciones insulares, un proceso \u00fanico de evoluci\u00f3n de pueblos amaziges procedentes del Norte de \u00c1frica, que vivieron en aislamiento hasta su conquista por la Corona de Castilla en el siglo XV. El cr\u00e1ter volc\u00e1nico de la Caldera de Tejeda preside este espacio, que se extiende a trav\u00e9s de los municipios de Artenara, Tejeda, Agaete y Galdar.<\/p>\n<p>La UNESCO reconoce el valor universal excepcional de la candidatura y destaca la pervivencia de usos tradicionales de las comunidades primitivas, como la trashumancia, el cultivo en bancales o la gesti\u00f3n del agua, as\u00ed como su estrecha vinculaci\u00f3n con la escarpada orograf\u00eda y las particularidades del paisaje, al que confirieron un car\u00e1cter sagrado muy unido al cielo y a la observaci\u00f3n de los fen\u00f3menos astron\u00f3micos. Es el primer bien ligado a la cultura amazige norteafricana que se inscribe en la lista.<\/p>\n<p>Las Monta\u00f1as Sagradas de Gran Canaria son un paisaje cultural -definido por la UNESCO como una obra conjunta de la humanidad y la naturaleza-, formado por 1.500 cuevas, un millar de tri\u00e1ngulos p\u00fabicos rupestres -la mayor concentraci\u00f3n del mundo-, y vestigios que permiten hablar de un paisaje relicto y vivo a la vez plagado de templos, santuarios, graneros fortificados, necr\u00f3polis, asentamientos trogloditas verticales y viviendas en cuevas ocupadas en ocasiones de manera ininterrumpida desde hace siglos hasta la actualidad.<\/p>\n<p>La cueva de Risco Ca\u00eddo es el mejor ejemplo de este paisaje, una c\u00fapula paraboidal que muestra durante 180 d\u00edas al a\u00f1o un llamativo relato de im\u00e1genes gracias a la intervenci\u00f3n del Sol, la Luna y el retablo de 37 tri\u00e1ngulos p\u00fabicos, orificios y hornacinas.<\/p>\n<h3>Cerca de 1.100 bienes integran la Lista de Patrimonio Mundial<\/h3>\n<p>La Lista incluye 1.092 sitios de \u00abvalor universal excepcional\u00bb ubicados en 167 pa\u00edses. Este a\u00f1o se han presentado un total de 37 candidaturas para su posible inscripci\u00f3n en la Lista de Patrimonio Mundial. De ellas, 6 corresponden a bienes de tipo natural, 30 son de car\u00e1cter cultural y 2 de naturaleza mixta (con valores naturales y culturales simult\u00e1neamente). Adem\u00e1s de Risco Ca\u00eddo, entre los bienes ya inscritos se encuentran Babilonia (Irak), los territorios y mares australes de Francia, el Parque Nacional del Vatnaj\u00f6kull (Islandia), los sitios de la antigua metalurgia del hierro de Burkina Faso (Burkina Faso), Bagan (Myanmar), los petroglifos y pictogramas del pueblo Siksik\u00e1\u00edtsitapi (Canad\u00e1) y el sistema de gesti\u00f3n del agua de Augsburgo (Alemania).<\/p>\n<h3>Pr\u00f3ximas candidaturas espa\u00f1olas<\/h3>\n<p>En 2020, Espa\u00f1a espera llevar al Comit\u00e9 la candidatura &#8216;Paseo del Prado y el Retiro. Paisaje de las Artes y las Ciencias&#8217;, de Madrid. Y, en 2021, est\u00e1 previsto que acuda al Comit\u00e9 Mundial con la propuesta del paisaje cultural de la Ribeira Sacra (Ourense y Lugo), decisi\u00f3n adoptada en el Consejo de Patrimonio Hist\u00f3rico celebrado el pasado mes de abril.<\/p>\n<p>Una web para difundir el patrimonio: somospatrimonio.es<br \/>\nPara divulgar todos los bienes declarados Patrimonio Mundial, especialmente entre el p\u00fablico joven, el Ministerio de Cultura y Deporte ha creado la web SomosPatrimonio (www.somospatrimonio.es).<\/p>\n<p>SomosPatrimonio.es destaca la variedad y riqueza del patrimonio cultural espa\u00f1ol, que incluye monumentos, paisajes y ciudades y comprende manifestaciones art\u00edsticas desde la Prehistoria hasta el siglo XX.<\/p>\n<p>A la web se incorporar\u00e1 en los pr\u00f3ximos d\u00edas Risco Ca\u00eddo y las monta\u00f1as sagradas de Gran Canaria.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo<\/p>\n","protected":false},"author":1,"featured_media":126100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126099","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-08T10:18:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-08T10:18:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#listItem\",\"name\":\"Risco Ca\\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#listItem\",\"position\":3,\"name\":\"Risco Ca\\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#newsarticle\",\"name\":\"Risco Ca\\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\\u00e1s 365\",\"headline\":\"Risco Ca\\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/040619-SedeUnesco.jpg\",\"width\":512,\"height\":340},\"datePublished\":\"2019-07-08T10:18:30+02:00\",\"dateModified\":\"2019-07-08T10:18:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 8, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/\",\"name\":\"Risco Ca\\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\\u00e1s 365\",\"description\":\"El Comit\\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\\u00eddo y el paisaje cultural de las monta\\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\\u00edces en la poblaci\\u00f3n del Norte de \\u00c1frica y logr\\u00f3 desarrollar una cultura propia en completo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/040619-SedeUnesco.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#mainImage\",\"width\":512,\"height\":340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\\\/#mainImage\"},\"datePublished\":\"2019-07-08T10:18:30+02:00\",\"dateModified\":\"2019-07-08T10:18:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365","description":"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo","canonical_url":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#listItem","name":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#listItem","position":3,"name":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#newsarticle","name":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365","headline":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg","width":512,"height":340},"datePublished":"2019-07-08T10:18:30+02:00","dateModified":"2019-07-08T10:18:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 8, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#webpage","url":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/","name":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365","description":"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg","@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#mainImage","width":512,"height":340},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/#mainImage"},"datePublished":"2019-07-08T10:18:30+02:00","dateModified":"2019-07-08T10:18:30+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365","og:description":"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo","og:url":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg","og:image:width":512,"og:image:height":340,"article:published_time":"2019-07-08T10:18:30+00:00","article:modified_time":"2019-07-08T10:18:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO | Cand\u00e1s 365","twitter:description":"El Comit\u00e9 de Patrimonio Mundial de la UNESCO ha incluido Risco Ca\u00eddo y el paisaje cultural de las monta\u00f1as sagradas de Gran Canaria en la Lista de Patrimonio Mundial, un reconocimiento a la antigua sociedad canaria, que hunde sus ra\u00edces en la poblaci\u00f3n del Norte de \u00c1frica y logr\u00f3 desarrollar una cultura propia en completo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/07\/040619-SedeUnesco.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"126099","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 12:49:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:55:14","updated":"2026-05-24 12:49:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tRisco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Risco Ca\u00eddo entra en la Lista de Patrimonio Mundial de la UNESCO","link":"https:\/\/candas365.es\/noticias\/risco-caido-entra-en-la-lista-de-patrimonio-mundial-de-la-unesco\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126099"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/126100"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}