{"id":123306,"date":"2019-05-28T17:17:18","date_gmt":"2019-05-28T17:17:18","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=123306"},"modified":"2019-05-28T17:17:18","modified_gmt":"2019-05-28T17:17:18","slug":"barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/","title":{"rendered":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-123307\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-768x422.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-655x360.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-696x385.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720-765x420.jpg 765w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 28 may (dpa) &#8211; Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles \u00abMade in GSA\u00bb celebrado en Berl\u00edn.<\/p>\n<p>Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada \u00abL\u00fcbsche Luft\u00bb, que consiste, entre otras cosas, en aguardiente de alcaravea, aguardiente de pepinillos y zumo de lim\u00f3n.<\/p>\n<p>\u00abMi homenaje al amado norte en forma de c\u00f3ctel\u00bb, dijo van Wyk, del bar \u00abDietrich&#8217;s\u00bb de L\u00fcbeck, seg\u00fan la citaron los organizadores.<\/p>\n<p>Por su parte, Valent\u00edn Bernauer, de 21 a\u00f1os y del bar \u00abBotanical Garden\u00bb (Jard\u00edn Bot\u00e1nico) de la capital austriaca, Viena, se llev\u00f3 el primer premio con su c\u00f3ctel \u00abTschi Es Ej\u00bb, que lleva vermut, aguardiente de pino suizo, vinagre de tomate y agua t\u00f3nica, entre otros ingredientes.<\/p>\n<p>El concurso de bebidas con el nombre ingl\u00e9s \u00abMade in GSA\u00bb (hecho en GSA, las siglas de Alemania, Suiza y Austria en ingl\u00e9s) promueve productos de bar locales y regionales de Alemania, Austria y Suiza y est\u00e1 considerado como el mayor concurso de c\u00f3cteles multimarca del mundo germanoparlante.<\/p>\n<p>Un total de once barmans llegaron a la final. A diferencia de otros a\u00f1os donde casi la mitad de los finalistas han sido mujeres, esta vez hubo s\u00f3lo una mujer en la final. Los organizadores explicaron que esto fue casual ya que la preselecci\u00f3n se realiz\u00f3 de manera an\u00f3nima.<\/p>\n<p>El lema del concurso de la revista de cultura de bar \u00abMixology\u00bb es \u00abHeimat im Glas\u00bb (la patria en el vaso). El jurado de cuatro miembros estaba compuesto esta vez por los expertos en c\u00f3cteles Charles Schumann (\u00abSchumann&#8217;s\u00bb\/M\u00fanich), Thomas Huhn (\u00abBar Les Trois Rois\u00bb\/Basilea), Gerhard Tsai (\u00abT\u00fcr 7&#8243;\/Viena) y Ruben Neideck (\u00abVelvet\u00bb\/Berl\u00edn).<\/p>\n<p>El certamen cont\u00f3 con el apoyo de casi 40 productores de bebidas alcoh\u00f3licas de Alemania, Austria y Suiza, que suministraron sus productos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 28 may (dpa) &#8211; Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles \u00abMade in GSA\u00bb celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada \u00abL\u00fcbsche Luft\u00bb, que consiste, entre otras<\/p>\n","protected":false},"author":1,"featured_media":123307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":{"0":"post-123306","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-revista"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles &quot;Made in GSA&quot; celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada &quot;L\u00fcbsche Luft&quot;, que consiste, entre otras\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles &quot;Made in GSA&quot; celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada &quot;L\u00fcbsche Luft&quot;, que consiste, entre otras\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-28T17:17:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-28T17:17:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles &quot;Made in GSA&quot; celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada &quot;L\u00fcbsche Luft&quot;, que consiste, entre otras\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#listItem\",\"name\":\"Barman alemana logra el segundo puesto en un concurso de c\\u00f3cteles de Berl\\u00edn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#listItem\",\"position\":3,\"name\":\"Barman alemana logra el segundo puesto en un concurso de c\\u00f3cteles de Berl\\u00edn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#newsarticle\",\"name\":\"Barman alemana logra el segundo puesto en un concurso de c\\u00f3cteles de Berl\\u00edn | Cand\\u00e1s 365\",\"headline\":\"Barman alemana logra el segundo puesto en un concurso de c\\u00f3cteles de Berl\\u00edn\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/drink-1870139_960_720.jpg\",\"width\":960,\"height\":527},\"datePublished\":\"2019-05-28T17:17:18+02:00\",\"dateModified\":\"2019-05-28T17:17:18+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#webpage\"},\"articleSection\":\"Revista\",\"dateline\":\"Publicado el mayo 28, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/\",\"name\":\"Barman alemana logra el segundo puesto en un concurso de c\\u00f3cteles de Berl\\u00edn | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 28 may (dpa) - Una barman de la ciudad de L\\u00fcbeck se hizo con el segundo lugar en la s\\u00e9ptima edici\\u00f3n del concurso de c\\u00f3cteles \\\"Made in GSA\\\" celebrado en Berl\\u00edn. Natalie van Wyk, de 25 a\\u00f1os y \\u00fanica mujer en la final, convenci\\u00f3 con su bebida llamada \\\"L\\u00fcbsche Luft\\\", que consiste, entre otras\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/drink-1870139_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#mainImage\",\"width\":960,\"height\":527},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\\\/#mainImage\"},\"datePublished\":\"2019-05-28T17:17:18+02:00\",\"dateModified\":\"2019-05-28T17:17:18+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365","description":"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles \"Made in GSA\" celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada \"L\u00fcbsche Luft\", que consiste, entre otras","canonical_url":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#listItem","name":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#listItem","position":3,"name":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#newsarticle","name":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365","headline":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg","width":960,"height":527},"datePublished":"2019-05-28T17:17:18+02:00","dateModified":"2019-05-28T17:17:18+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#webpage"},"articleSection":"Revista","dateline":"Publicado el mayo 28, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#webpage","url":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/","name":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365","description":"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles \"Made in GSA\" celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada \"L\u00fcbsche Luft\", que consiste, entre otras","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#mainImage","width":960,"height":527},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/#mainImage"},"datePublished":"2019-05-28T17:17:18+02:00","dateModified":"2019-05-28T17:17:18+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365","og:description":"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles &quot;Made in GSA&quot; celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada &quot;L\u00fcbsche Luft&quot;, que consiste, entre otras","og:url":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg","og:image:width":960,"og:image:height":527,"article:published_time":"2019-05-28T17:17:18+00:00","article:modified_time":"2019-05-28T17:17:18+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 28 may (dpa) - Una barman de la ciudad de L\u00fcbeck se hizo con el segundo lugar en la s\u00e9ptima edici\u00f3n del concurso de c\u00f3cteles &quot;Made in GSA&quot; celebrado en Berl\u00edn. Natalie van Wyk, de 25 a\u00f1os y \u00fanica mujer en la final, convenci\u00f3 con su bebida llamada &quot;L\u00fcbsche Luft&quot;, que consiste, entre otras","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/drink-1870139_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"123306","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 00:46:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:57:07","updated":"2025-08-30 00:46:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tBarman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"Barman alemana logra el segundo puesto en un concurso de c\u00f3cteles de Berl\u00edn","link":"https:\/\/candas365.es\/noticias\/barman-alemana-logra-el-segundo-puesto-en-un-concurso-de-cocteles-de-berlin\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/123306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=123306"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/123306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/123307"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=123306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=123306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=123306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}