{"id":123027,"date":"2019-05-23T17:07:22","date_gmt":"2019-05-23T17:07:22","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=123027"},"modified":"2019-05-23T17:07:22","modified_gmt":"2019-05-23T17:07:22","slug":"comienza-la-gira-de-los-backstreet-boys-por-alemania","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/","title":{"rendered":"Comienza la gira de los Backstreet Boys por Alemania"},"content":{"rendered":"<figure id=\"attachment_123033\" aria-describedby=\"caption-attachment-123033\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-123033\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-360x179.jpg\" alt=\"\" width=\"360\" height=\"179\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-360x179.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-768x381.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-655x325.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-324x160.jpg 324w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-696x346.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-1068x530.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys-846x420.jpg 846w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg 1152w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-123033\" class=\"wp-caption-text\">Foto: Christophe Gateau\/dpa<\/figcaption><\/figure>\n<p>Hannover (Alemania), 22 may (dpa) &#8211; El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover.<\/p>\n<p>La gira titulada \u00abBackstreet&#8217;s Back\u00bb, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.<\/p>\n<p>Los integrantes del grupo, que antes hicieron gritar a los adolescentes, son ahora padres de familia.<\/p>\n<p>Para su \u00e1lbum \u00abDNA\u00bb, lanzado en enero, los miembros de la banda analizaron su material gen\u00e9tico.<\/p>\n<p>Seg\u00fan el organizador de la gira, esta es la mayor serie de conciertos en recintos cubiertos de los Backstreet Boys en 18 a\u00f1os.<\/p>\n<p>La banda consigui\u00f3 numerosos \u00e9xitos internacionales como \u00abQuit Playin &#8216;Games With My Heart\u00bb o \u00abI Want It That Way\u00bb. Seg\u00fan su sello discogr\u00e1fico, se trata del \u00abBoygroup\u00bb m\u00e1s exitoso del mundo con m\u00e1s de 130 millones de discos vendidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hannover (Alemania), 22 may (dpa) &#8211; El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada \u00abBackstreet&#8217;s Back\u00bb, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.<\/p>\n","protected":false},"author":1,"featured_media":123033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":{"0":"post-123027","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-revista"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada &quot;Backstreet&#039;s Back&quot;, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada &quot;Backstreet&#039;s Back&quot;, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-23T17:07:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-05-23T17:07:22+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada &quot;Backstreet&#039;s Back&quot;, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#listItem\",\"name\":\"Comienza la gira de los Backstreet Boys por Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#listItem\",\"position\":3,\"name\":\"Comienza la gira de los Backstreet Boys por Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#newsarticle\",\"name\":\"Comienza la gira de los Backstreet Boys por Alemania | Cand\\u00e1s 365\",\"headline\":\"Comienza la gira de los Backstreet Boys por Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Backstreet-Boys.jpg\",\"width\":1152,\"height\":572,\"caption\":\"Foto: Christophe Gateau\\\/dpa\"},\"datePublished\":\"2019-05-23T17:07:22+02:00\",\"dateModified\":\"2019-05-23T17:07:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#webpage\"},\"articleSection\":\"Revista\",\"dateline\":\"Publicado el mayo 23, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/\",\"name\":\"Comienza la gira de los Backstreet Boys por Alemania | Cand\\u00e1s 365\",\"description\":\"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\\u00f3 el martes su gira por Alemania despu\\u00e9s de varios a\\u00f1os con un concierto en la ciudad de Hannover. La gira titulada \\\"Backstreet's Back\\\", llevar\\u00e1 a la banda que triunf\\u00f3 a finales de la d\\u00e9cada de 1990 a Mannheim, M\\u00fanich, Berl\\u00edn y Colonia.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Backstreet-Boys.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#mainImage\",\"width\":1152,\"height\":572,\"caption\":\"Foto: Christophe Gateau\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/comienza-la-gira-de-los-backstreet-boys-por-alemania\\\/#mainImage\"},\"datePublished\":\"2019-05-23T17:07:22+02:00\",\"dateModified\":\"2019-05-23T17:07:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365","description":"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada \"Backstreet's Back\", llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.","canonical_url":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#listItem","name":"Comienza la gira de los Backstreet Boys por Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#listItem","position":3,"name":"Comienza la gira de los Backstreet Boys por Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#newsarticle","name":"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365","headline":"Comienza la gira de los Backstreet Boys por Alemania","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg","width":1152,"height":572,"caption":"Foto: Christophe Gateau\/dpa"},"datePublished":"2019-05-23T17:07:22+02:00","dateModified":"2019-05-23T17:07:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#webpage"},"articleSection":"Revista","dateline":"Publicado el mayo 23, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#webpage","url":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/","name":"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365","description":"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada \"Backstreet's Back\", llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg","@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#mainImage","width":1152,"height":572,"caption":"Foto: Christophe Gateau\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/#mainImage"},"datePublished":"2019-05-23T17:07:22+02:00","dateModified":"2019-05-23T17:07:22+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365","og:description":"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada &quot;Backstreet's Back&quot;, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.","og:url":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg","og:image:width":1152,"og:image:height":572,"article:published_time":"2019-05-23T17:07:22+00:00","article:modified_time":"2019-05-23T17:07:22+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Comienza la gira de los Backstreet Boys por Alemania | Cand\u00e1s 365","twitter:description":"Hannover (Alemania), 22 may (dpa) - El grupo musical estadounidense Backstreet Boys inici\u00f3 el martes su gira por Alemania despu\u00e9s de varios a\u00f1os con un concierto en la ciudad de Hannover. La gira titulada &quot;Backstreet's Back&quot;, llevar\u00e1 a la banda que triunf\u00f3 a finales de la d\u00e9cada de 1990 a Mannheim, M\u00fanich, Berl\u00edn y Colonia.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/05\/Backstreet-Boys.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"123027","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 00:03:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:57:16","updated":"2025-08-30 00:03:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tComienza la gira de los Backstreet Boys por Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"Comienza la gira de los Backstreet Boys por Alemania","link":"https:\/\/candas365.es\/noticias\/comienza-la-gira-de-los-backstreet-boys-por-alemania\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/123027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=123027"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/123027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/123033"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=123027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=123027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=123027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}