{"id":121537,"date":"2019-04-27T21:08:54","date_gmt":"2019-04-27T21:08:54","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=121537"},"modified":"2019-04-27T21:08:54","modified_gmt":"2019-04-27T21:08:54","slug":"leonardo-da-vinci-y-las-mujeres-de-kia-vahland","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/","title":{"rendered":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland"},"content":{"rendered":"<figure id=\"attachment_121538\" aria-describedby=\"caption-attachment-121538\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-121538\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-360x269.jpg\" alt=\"\" width=\"360\" height=\"269\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-360x269.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-768x574.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-642x480.jpg 642w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-696x520.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland-562x420.jpg 562w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg 875w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-121538\" class=\"wp-caption-text\">Foto: Jens Kalaene\/dpa-Zentralbild\/dpa<\/figcaption><\/figure>\n<p>Berl\u00edn, 26 abr (dpa) &#8211; Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland.<\/p>\n<p>Las convenciones no juegan ning\u00fan papel: Leonardo abandona la representaci\u00f3n habitual de perfil y dirige sus figuras hacia el espectador, las secuestra de habitaciones cerradas y las coloca en un paisaje. Sus mujeres son personalidades independientes.<\/p>\n<p>En su libro \u00abLeonardo da Vinci y las mujeres\u00bb, Vahland describe c\u00f3mo el pintor renacentista transmite una nueva perspectiva. Desde la imagen de una muy segura Mar\u00eda en la Anunciaci\u00f3n, pasando por Ginevra de Benci, \u00abel primer retrato psicol\u00f3gico\u00bb, hasta llegar a la Mona Lisa, \u00abel cuadro m\u00e1s influyente de Occidente\u00bb.<\/p>\n<p>La historiadora del arte ha logrado producir una obra muy completa del pintor italiano al cumplirse el 500 aniversario de su muerte el 2 de mayo.<\/p>\n<p>Leonardo naci\u00f3 en 1452 como hijo ileg\u00edtimo, un estigma en la Italia del Renacimiento. En su pueblo disfruta de la libertad y todo le resulta interesante. Su formaci\u00f3n comienza en Florencia, donde muchos artistas estaban abiertos a nuevas ideas.<\/p>\n<p>Leonardo pas\u00f3 luego varios a\u00f1os en Mil\u00e1n y alrededor del a\u00f1o 1500 regres\u00f3 a Florencia. Hab\u00eda dejado la ciudad como un \u00abhombre incomprendido, ahora es uno de los hombres m\u00e1s famosos de su tiempo\u00bb, apunta la historiadora en la biograf\u00eda del pintor italiano.<\/p>\n<p>Vahland tambi\u00e9n explica por qu\u00e9 Leonardo era distinto a los dem\u00e1s. \u00abAl igual que sus or\u00edgenes ileg\u00edtimos, su vegetarianismo, su amor por los animales y la naturaleza, algo inusual en su \u00e9poca, el pintor tambi\u00e9n era distinto en su vida privada\u00bb.<\/p>\n<p>El artista, que ama a los hombres y emplea \u00absiempre a j\u00f3venes nuevos y guapos\u00bb, no se deja perturbar. Especialmente en su respeto por las mujeres, una postura inusual en su \u00e9poca, se\u00f1ala Vahland.<\/p>\n<p>Esto tambi\u00e9n se puede ver en la pintura de la modelo Cecilia Gallerani, a la cual Leonardo pinta con un armi\u00f1o en el brazo. La historiadora explica su trabajo y simbolismo en detalle.<\/p>\n<p>La imagen m\u00e1s famosa del mundo, la Mona Lisa, tambi\u00e9n est\u00e1 descrita en detalle: \u00abElla se convierte en la figura principal de su vida y obra (&#8230;.)\u00bb. Vahland describe c\u00f3mo fue creado el retrato y de qu\u00e9 se trata la sonrisa de la Mona Lisa.<\/p>\n<p>Una y otra vez, el trabajo y la vida de Leonardo da Vinci se ven insertos en el desarrollo hist\u00f3rico y social. En el ep\u00edlogo, la autora se refiere brevemente al mercado del arte, en el que supuestas obras del pintor alcanzan los mejores precios. El n\u00famero de \u00abcuadros y bocetos realizadas por Leonardo\u00bb es sorprendentemente peque\u00f1o. Vahland estima que son diecis\u00e9is.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 26 abr (dpa) &#8211; Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la<\/p>\n","protected":false},"author":1,"featured_media":121538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":{"0":"post-121537","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-revista"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"875\" \/>\n\t\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-27T21:08:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-27T21:08:54+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#listItem\",\"name\":\"\\u00abLeonardo da Vinci y las mujeres\\u00bb de Kia Vahland\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#listItem\",\"position\":3,\"name\":\"\\u00abLeonardo da Vinci y las mujeres\\u00bb de Kia Vahland\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#newsarticle\",\"name\":\"\\u00abLeonardo da Vinci y las mujeres\\u00bb de Kia Vahland | Cand\\u00e1s 365\",\"headline\":\"\\u00abLeonardo da Vinci y las mujeres\\u00bb de Kia Vahland\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Kia-Vahland.jpg\",\"width\":875,\"height\":654,\"caption\":\"Foto: Jens Kalaene\\\/dpa-Zentralbild\\\/dpa\"},\"datePublished\":\"2019-04-27T21:08:54+02:00\",\"dateModified\":\"2019-04-27T21:08:54+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#webpage\"},\"articleSection\":\"Revista\",\"dateline\":\"Publicado el abril 27, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/\",\"name\":\"\\u00abLeonardo da Vinci y las mujeres\\u00bb de Kia Vahland | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\\u00fan papel: Leonardo abandona la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Kia-Vahland.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#mainImage\",\"width\":875,\"height\":654,\"caption\":\"Foto: Jens Kalaene\\\/dpa-Zentralbild\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\\\/#mainImage\"},\"datePublished\":\"2019-04-27T21:08:54+02:00\",\"dateModified\":\"2019-04-27T21:08:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365","description":"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la","canonical_url":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#listItem","name":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#listItem","position":3,"name":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#newsarticle","name":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365","headline":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg","width":875,"height":654,"caption":"Foto: Jens Kalaene\/dpa-Zentralbild\/dpa"},"datePublished":"2019-04-27T21:08:54+02:00","dateModified":"2019-04-27T21:08:54+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#webpage"},"articleSection":"Revista","dateline":"Publicado el abril 27, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#webpage","url":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/","name":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365","description":"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg","@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#mainImage","width":875,"height":654,"caption":"Foto: Jens Kalaene\/dpa-Zentralbild\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/#mainImage"},"datePublished":"2019-04-27T21:08:54+02:00","dateModified":"2019-04-27T21:08:54+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365","og:description":"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la","og:url":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg","og:image:width":875,"og:image:height":654,"article:published_time":"2019-04-27T21:08:54+00:00","article:modified_time":"2019-04-27T21:08:54+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 26 abr (dpa) - Las mujeres y la naturaleza son las protagonistas de los cuadros de Leonardo da Vinci. El artista italiano (1452-1519) les concede un respeto especial porque ambas pueden dar vida y crear algo nuevo, asegura la historiadora del arte alemana Kia Vahland. Las convenciones no juegan ning\u00fan papel: Leonardo abandona la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/Kia-Vahland.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"121537","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 20:20:30","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:47:57","updated":"2025-08-29 20:20:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"\u00abLeonardo da Vinci y las mujeres\u00bb de Kia Vahland","link":"https:\/\/candas365.es\/noticias\/leonardo-da-vinci-y-las-mujeres-de-kia-vahland\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/121537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=121537"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/121537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/121538"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=121537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=121537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=121537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}