{"id":120823,"date":"2019-04-15T16:39:26","date_gmt":"2019-04-15T16:39:26","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=120823"},"modified":"2019-04-15T16:39:26","modified_gmt":"2019-04-15T16:39:26","slug":"los-rincones-mas-secretos-en-barcelona","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/","title":{"rendered":"Los rincones m\u00e1s secretos en Barcelona"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-120824\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona-360x216.jpg\" alt=\"\" width=\"360\" height=\"216\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona-360x216.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona-655x393.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona-696x418.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona-700x420.jpg 700w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg 750w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos rincones que est\u00e1n tan escondidos que solo los m\u00e1s audaces son capaces de descubrir.<\/p>\n<h3><strong>Descubre la Ciudad Condal<\/strong><\/h3>\n<p>En esta encantadora ciudad, es muy f\u00e1cil dejarse seducir por sus lugares populares, rincones que siempre est\u00e1n repletos de turistas que disfrutan, pero definitivamente para poder vivirla, lo mejor es conocerla. En este caso, lo ideal es <span style=\"color: #ff6600;\"><strong><a style=\"color: #ff6600;\" href=\"https:\/\/www.quehacerenbcn.com\/es\/otros\/otros\/top-qhe-rincones-secretos-de-barcelona\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.quehacerenbcn.com\/es\/otros\/otros\/top-qhe-rincones-secretos-de-barcelona<\/a><\/strong><\/span>. Aqu\u00ed se descubren esos lugares ocultos que hacen a\u00fan m\u00e1s apetecible esta cosmopolita.<\/p>\n<p>Existen sitios en Barcelona que <strong>encierran en s\u00ed una historia a\u00fan m\u00e1s excitante que la ciudad misma<\/strong>. A continuaci\u00f3n, ent\u00e9rate de algunos de ellos.<\/p>\n<h4><strong>Hospital Sant Creu i Sant Pau<\/strong><\/h4>\n<p>Una edificaci\u00f3n que data del siglo XIX, fundado como un hospital. Considerado hoy por muchos como <strong>uno de los monumentos con dise\u00f1o modernista m\u00e1s grande de todo Europa<\/strong>. Ha sido el lugar ideal para conciertos de m\u00fasica cl\u00e1sica durante los fines de semana, pero de igual manera si se quiere se puede realizar una visita dirigida por los gu\u00edas del lugar. As\u00ed que para adentrarse a la arquitectura antigua, este es uno de los sitios ocultos de Barcelona que no se puede dejar de visitar.<\/p>\n<h4><strong>Los B\u00fankers del Carmel<\/strong><\/h4>\n<p>Ubicados en la cima del Tur\u00f3 de la Rovira, se encuentran los restos de una bater\u00eda antia\u00e9rea de la Guerra Civil Espa\u00f1ola. Aparte de ser un lugar con un aura de historia, <strong>es el sitio ideal para disfrutar de una de las vistas m\u00e1s impactantes de la capital de Catalu\u00f1a<\/strong>. Lo mejor de todo es que a los b\u00fankers se puede llegar sencillamente andando unos cuantos minutos por una subida hacia el barrio El Carmel o bien tomando el autob\u00fas V17.<\/p>\n<h4><strong>Museo er\u00f3tico<\/strong><\/h4>\n<p>Con m\u00e1s de 800 piezas dedicadas exclusivamente a la sexualidad y erotismo, en este museo, que no es apto para menores de 18 a\u00f1os, cada una de las obras cuenta una historia representada por <strong>el erotismo m\u00e1s crudo visto desde las diferentes culturas del mundo<\/strong>. Se encuentra ubicado en La Rambla 96 bis, y es uno de esos lugares que bien sea por curiosidad, por turismo o amor al arte, no se puede dejar de visitar en Barcelona.<\/p>\n<h4><strong>Terrazas del Palau G\u00fcell<\/strong><\/h4>\n<p>Continuando la visita por Barcelona y sus lugares ocultos, se encuentra una de las obras m\u00e1s alucinantes del arquitecto modernista catal\u00e1n Antoni Gaud\u00ed, el Palau G\u00fcell, <strong>caracter\u00edstico por sus colores en las chimeneas de su terraza<\/strong>, este m\u00e1gico lugar de extra\u00f1as formas y cubierto por mosaicos impresionantes. Este impresionante lugar se encuentra en la calle Nou de Las Ramblas.<\/p>\n<h4><strong>Convento de Sant Agust\u00ed<\/strong><\/h4>\n<p>Con un alto valor arquitect\u00f3nico e hist\u00f3rico, este convento fue construido en el siglo XIV, pero no solo sirvi\u00f3 como claustro, sino que tambi\u00e9n este recinto g\u00f3tico tuvo otras funciones, entre ellas, un horno de pan y centro gremial. En la actualidad es utilizado para espect\u00e1culos, actividades culturales y algunos talleres art\u00edsticos. <strong>Durante los fines de semana realizan ferias que son un verdadero gusto<\/strong>.<\/p>\n<h4><strong>Templo de Augusto<\/strong><\/h4>\n<p>En lo m\u00e1s alto del monte Taber se encuentra este fascinante lugar. <strong>Fue construido en el Siglo I a.C., cuando esas tierras eran parte del Imperio Romano,<\/strong> como un culto para el emperador C\u00e9sar Augusto. Para llegar a este recinto, es necesario tomar la calle Carrer Parad\u00eds por el Barrio G\u00f3tico.<\/p>\n<h4><strong>Museo de carrozas f\u00fanebres<\/strong><\/h4>\n<p>Para los amantes de lo l\u00fagubre y fantasmal, Barcelona tambi\u00e9n tiene lugares ocultos especialmente para ellos. Desde el a\u00f1o 2013 existe en el Cementerio de Montjuic la Colecci\u00f3n de Carrozas F\u00fanebres. Son al menos 19 antiguos carruajes con carteles que cuentan una interesante historia. A pesar de lo terror\u00edfico que pueda parecer, es una de las exposiciones m\u00e1s originales de la ciudad.<\/p>\n<h4><strong>La Cafeter\u00eda del Museo Frederic Mar\u00e8s<\/strong><\/h4>\n<p>Ubicada en la Plaza San Iu 5, este id\u00edlico lugar se encuentra del mismo museo, <strong>es un verdadero para\u00edso en medio de lo g\u00f3tico y cotidiano de la ciudad de Barcelona<\/strong>, sentarse a tomar un caf\u00e9 o saborear un trozo de delicioso pastel mientras se observa la arquitectura que lo rodea y la c\u00fapula de la Catedral es una experiencia de lo m\u00e1s placentera.<\/p>\n<h4><strong>La Estatua de la Libertad<\/strong><\/h4>\n<p>Aunque la imagen que seguro viene a la mente es la de Nueva York, en Barcelona tambi\u00e9n hay una Estatua de la Libertad, pero esta se encuentra en el interior de la Biblioteca Ar\u00fas, relacionada con la Masoner\u00eda. <strong>Con m\u00e1s de 120 a\u00f1os de antig\u00fcedad<\/strong>, esta r\u00e9plica de la que se encuentra en Estados Unidos es poco conocida por los turistas, debido a que no est\u00e1 en un lugar muy concurrido. Direcci\u00f3n: Paseo San Juan 26.<\/p>\n<p>Estos son algunos de los maravillosos lugares ocultos con los que cuenta Barcelona, y qu\u00e9 importante es recordarlos al momento de estar de visita por esta fascinante ciudad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos<\/p>\n","protected":false},"author":1,"featured_media":120824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":{"0":"post-120823","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-revista"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-15T16:39:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-15T16:39:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#listItem\",\"name\":\"Los rincones m\\u00e1s secretos en Barcelona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#listItem\",\"position\":3,\"name\":\"Los rincones m\\u00e1s secretos en Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#newsarticle\",\"name\":\"Los rincones m\\u00e1s secretos en Barcelona | Cand\\u00e1s 365\",\"headline\":\"Los rincones m\\u00e1s secretos en Barcelona\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/9317-ndp-Barcelona.jpg\",\"width\":750,\"height\":450},\"datePublished\":\"2019-04-15T16:39:26+02:00\",\"dateModified\":\"2019-04-15T16:39:26+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#webpage\"},\"articleSection\":\"Revista\",\"dateline\":\"Publicado el abril 15, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/\",\"name\":\"Los rincones m\\u00e1s secretos en Barcelona | Cand\\u00e1s 365\",\"description\":\"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\\u00e1s enigm\\u00e1tica y encantadora del mundo, no es de extra\\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/9317-ndp-Barcelona.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#mainImage\",\"width\":750,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-rincones-mas-secretos-en-barcelona\\\/#mainImage\"},\"datePublished\":\"2019-04-15T16:39:26+02:00\",\"dateModified\":\"2019-04-15T16:39:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365","description":"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos","canonical_url":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#listItem","name":"Los rincones m\u00e1s secretos en Barcelona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#listItem","position":3,"name":"Los rincones m\u00e1s secretos en Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#newsarticle","name":"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365","headline":"Los rincones m\u00e1s secretos en Barcelona","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg","width":750,"height":450},"datePublished":"2019-04-15T16:39:26+02:00","dateModified":"2019-04-15T16:39:26+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#webpage"},"articleSection":"Revista","dateline":"Publicado el abril 15, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#webpage","url":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/","name":"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365","description":"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg","@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#mainImage","width":750,"height":450},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/#mainImage"},"datePublished":"2019-04-15T16:39:26+02:00","dateModified":"2019-04-15T16:39:26+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365","og:description":"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos","og:url":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg","og:image:width":750,"og:image:height":450,"article:published_time":"2019-04-15T16:39:26+00:00","article:modified_time":"2019-04-15T16:39:26+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Los rincones m\u00e1s secretos en Barcelona | Cand\u00e1s 365","twitter:description":"Cuando se trata de disfrutar una ciudad llena de rincones fascinantes, historia y secretos, Barcelona es el destino. Considerada por muchos turistas como la ciudad m\u00e1s enigm\u00e1tica y encantadora del mundo, no es de extra\u00f1ar que sus lugares no dejen de sorprender y que con un simple viaje no sea suficiente para poder conocer esos","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/9317-ndp-Barcelona.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"120823","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 18:19:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:58:41","updated":"2025-08-29 18:19:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLos rincones m\u00e1s secretos en Barcelona\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"Los rincones m\u00e1s secretos en Barcelona","link":"https:\/\/candas365.es\/noticias\/los-rincones-mas-secretos-en-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=120823"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/120824"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=120823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=120823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=120823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}