{"id":120820,"date":"2019-04-14T20:44:14","date_gmt":"2019-04-14T20:44:14","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=120820"},"modified":"2019-04-14T20:44:14","modified_gmt":"2019-04-14T20:44:14","slug":"los-buses-inteligentes-a-la-conquista-de-las-ciudades","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/","title":{"rendered":"Los buses inteligentes, a la conquista de las ciudades"},"content":{"rendered":"<figure id=\"attachment_120821\" aria-describedby=\"caption-attachment-120821\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-120821\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-768x509.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-655x434.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-696x461.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes-633x420.jpg 633w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg 1015w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-120821\" class=\"wp-caption-text\">Un \u00abshuttle\u00bb inteligente de Urbanetic de Mercedes Foto: Daimler AG\/dpa-tmn<\/figcaption><\/figure>\n<p>Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de Las Vegas.<\/p>\n<p>Enero es el mes de los prodigios en Las Vegas, cuando se re\u00fane la feria de la electr\u00f3nica de consumo m\u00e1s importante del mundo. Si lo que se vio ah\u00ed se vuelve realidad, los autobuses y taxis, tal como se les conoce actualmente, pronto quedar\u00edan obsoletos.<\/p>\n<p>Las ciudades los sustituir\u00e1n por una red de \u00abrobo-shuttles\u00bb, buses inteligentes que recoger\u00e1n a los pasajeros donde \u00e9stos quieran y calcular\u00e1n autom\u00e1ticamente las rutas con base en las necesidades de los usuarios, para que el mayor n\u00famero posible de clientes llegue a su destino en el menor tiempo posible, explica Thomas Moser, uno de los responsables del proyecto Vision Urbanetic de Mercedes.<\/p>\n<p>El proyecto desarroll\u00f3 un veh\u00edculo al que se le permiti\u00f3 hacer un breve recorrido por Las Vegas. Durante una noche, un minib\u00fas aut\u00f3nomo subi\u00f3 y baj\u00f3 por la avenida m\u00e1s famosa de la ciudad y recogi\u00f3 en diferentes casinos a una decena de pasajeros, a los que transport\u00f3 a lo largo del \u00abStrip\u00bb.<\/p>\n<p>Wolfgang Bernhart, de la consultora Roland Berger, supone que estos veh\u00edculos dominar\u00e1n el paisaje urbano en la pr\u00f3xima d\u00e9cada y revolucionar\u00e1n el transporte p\u00fablico.<\/p>\n<p>\u00abSe aproxima una nueva generaci\u00f3n de medios de transporte que nos llevar\u00e1 a un nuevo tipo de movilidad\u00bb, afirma. \u00abEs exactamente igual que cuando el carro motorizado se convirti\u00f3 en el coche que conocemos hoy\u00bb.<\/p>\n<p>Los pasajeros tendr\u00e1n un viaje m\u00e1s seguro, m\u00e1s c\u00f3modo y, en el mejor de los casos, incluso m\u00e1s corto, dice Bernhart. Adem\u00e1s, ser\u00e1 m\u00e1s barato que un viaje en taxi. Y la sociedad se beneficiar\u00e1 de un menor n\u00famero de veh\u00edculos privados en las calles, lo que mejorar\u00e1 la fluidez del tr\u00e1nsito y reducir\u00e1 la contaminaci\u00f3n.<\/p>\n<p>Algunos fabricantes ya desarrollan sus flotas de veh\u00edculos de prueba. Bosch, Continental y ZF tienen minibuses aut\u00f3nomos y Volkswagen cuenta con un autob\u00fas robotizado, el Sedric. En otros sectores, como los de paqueter\u00eda, se est\u00e1 trabajando en la creaci\u00f3n de un servicio de entregas automatizado.<\/p>\n<p>Personas como Moser o el creativo suizo Frank Rinderknecht van un paso m\u00e1s all\u00e1. Para reducir aun m\u00e1s el n\u00famero de veh\u00edculos en las calles y, al mismo tiempo, maximizar su vida \u00fatil, se desarrollan incluso cambios de formato. Algunos veh\u00edculos pueden ser adaptados autom\u00e1ticamente, y en cuesti\u00f3n de minutos un autob\u00fas se convierte en cami\u00f3n de reparto.<\/p>\n<p>Los minibuses sin conductor ya est\u00e1n circulando en las instalaciones de grandes empresas privadas o universidades.<\/p>\n<p>Pronto dar\u00e1n servicio al transporte p\u00fablico. ZF anunci\u00f3 el primer pedido importante de su minib\u00fas aut\u00f3nomo, aunque la primera generaci\u00f3n probablemente necesitar\u00e1 un conductor, seg\u00fan Chrisoph Horn, responsable de prensa de la firma.<\/p>\n<p>\u00abPrimero, porque el software todav\u00eda est\u00e1 aprendiendo a interpretar la situaci\u00f3n del tr\u00e1nsito y, segundo, porque la ley obliga por el momento\u00bb, se\u00f1ala.<\/p>\n<p>Cuanto mejor funcionen los buses inteligentes y cuanto m\u00e1s cerca est\u00e9n del transporte p\u00fablico, por ejemplo de estaciones de tren, m\u00e1s dif\u00edcil ser\u00e1 el futuro para los autobuses y taxis convencionales.<\/p>\n<p>Bernhart dice que los coches todav\u00eda ser\u00e1n importantes. Cree que en alg\u00fan momento habr\u00e1 ciudades que prohibir\u00e1n completamente el transporte privado. Pero ser\u00e1 una excepci\u00f3n. \u00abEn nuestros escenarios, el coche ocupar\u00e1 su lugar durante mucho tiempo\u00bb, sentenci\u00f3.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Thomas Geiger (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de<\/p>\n","protected":false},"author":1,"featured_media":120821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":{"0":"post-120820","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-revista"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1015\" \/>\n\t\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-14T20:44:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-14T20:44:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#listItem\",\"name\":\"Los buses inteligentes, a la conquista de las ciudades\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#listItem\",\"position\":3,\"name\":\"Los buses inteligentes, a la conquista de las ciudades\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#newsarticle\",\"name\":\"Los buses inteligentes, a la conquista de las ciudades | Cand\\u00e1s 365\",\"headline\":\"Los buses inteligentes, a la conquista de las ciudades\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/buses-inteligentes.jpg\",\"width\":1015,\"height\":673,\"caption\":\"Un \\\"shuttle\\\" inteligente de Urbanetic de Mercedes Foto: Daimler AG\\\/dpa-tmn\"},\"datePublished\":\"2019-04-14T20:44:14+02:00\",\"dateModified\":\"2019-04-14T20:44:14+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#webpage\"},\"articleSection\":\"Revista\",\"dateline\":\"Publicado el abril 14, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/\",\"name\":\"Los buses inteligentes, a la conquista de las ciudades | Cand\\u00e1s 365\",\"description\":\"Suele ocurrir: hace fr\\u00edo, es de noche y el autob\\u00fas no llega. Y se detiene despu\\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\\u00f3nica CES de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/buses-inteligentes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#mainImage\",\"width\":1015,\"height\":673,\"caption\":\"Un \\\"shuttle\\\" inteligente de Urbanetic de Mercedes Foto: Daimler AG\\\/dpa-tmn\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\\\/#mainImage\"},\"datePublished\":\"2019-04-14T20:44:14+02:00\",\"dateModified\":\"2019-04-14T20:44:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365","description":"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de","canonical_url":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#listItem","name":"Los buses inteligentes, a la conquista de las ciudades"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#listItem","position":3,"name":"Los buses inteligentes, a la conquista de las ciudades","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#newsarticle","name":"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365","headline":"Los buses inteligentes, a la conquista de las ciudades","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg","width":1015,"height":673,"caption":"Un \"shuttle\" inteligente de Urbanetic de Mercedes Foto: Daimler AG\/dpa-tmn"},"datePublished":"2019-04-14T20:44:14+02:00","dateModified":"2019-04-14T20:44:14+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#webpage"},"articleSection":"Revista","dateline":"Publicado el abril 14, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#webpage","url":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/","name":"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365","description":"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg","@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#mainImage","width":1015,"height":673,"caption":"Un \"shuttle\" inteligente de Urbanetic de Mercedes Foto: Daimler AG\/dpa-tmn"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/#mainImage"},"datePublished":"2019-04-14T20:44:14+02:00","dateModified":"2019-04-14T20:44:14+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365","og:description":"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de","og:url":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg","og:image:width":1015,"og:image:height":673,"article:published_time":"2019-04-14T20:44:14+00:00","article:modified_time":"2019-04-14T20:44:14+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Los buses inteligentes, a la conquista de las ciudades | Cand\u00e1s 365","twitter:description":"Suele ocurrir: hace fr\u00edo, es de noche y el autob\u00fas no llega. Y se detiene despu\u00e9s en cada parada aunque nadie quiera subir o bajar. Pero las cosas podr\u00edan ser distintas en el futuro con una App para solicitar un bus, a tenor de lo que se pudo ver en la feria electr\u00f3nica CES de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/04\/buses-inteligentes.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"120820","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 18:19:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:58:41","updated":"2025-08-29 18:19:17"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLos buses inteligentes, a la conquista de las ciudades\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"Los buses inteligentes, a la conquista de las ciudades","link":"https:\/\/candas365.es\/noticias\/los-buses-inteligentes-a-la-conquista-de-las-ciudades\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=120820"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/120821"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=120820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=120820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=120820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}