{"id":120612,"date":"2019-04-12T04:47:21","date_gmt":"2019-04-12T04:47:21","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=120612"},"modified":"2019-04-12T04:47:21","modified_gmt":"2019-04-12T04:47:21","slug":"vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/","title":{"rendered":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-91805\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-1068x710.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China.<\/p>\n<p>\u00abMi carrera fue algo distinta a la suya en Bar\u00e9in, pero eso no tiene nada que ver con la motivaci\u00f3n para esta carrera\u00bb, declar\u00f3 el piloto de 31 a\u00f1os.<\/p>\n<p>\u00abQue uno quiera vencer a su compa\u00f1ero de equipo lo llevamos todos dentro, si no no estar\u00edamos aqu\u00ed. Este fin de semana partimos de cero, ya veremos d\u00f3nde estamos despu\u00e9s\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Sebastian Leclerc, de 21 a\u00f1os, obtuvo su primera pole en el Gran Premio de Bar\u00e9in, relegando a Vettel a la segunda posici\u00f3n. El piloto monegasco lleg\u00f3 a liderar la carrera, aunque un problema mec\u00e1nico le hizo acabar en la tercera posici\u00f3n, tras el defensor del t\u00edtulo Lewis Hamilton y el compa\u00f1ero de equipo Mercedes Valtteri Bottas.<\/p>\n<p>Vettel, por su parte, no fue capaz de superar la quinta posici\u00f3n. En la clasificaci\u00f3n del Mundial de la F\u00f3rmula 1, pr\u00f3ximo a celebrar su Gran Premio n\u00famero 1.000, Bottas se mantiene en primera posici\u00f3n por delante de Hamilton, mientras que Vettel es quinto, justo a cuatro puntos de Leclerc.<\/p>\n<p>En su primer a\u00f1o como piloto oficial de Ferrari tras una temporada en Sauber, el joven monegasco no se acostumbra a su nueva condici\u00f3n de favorito. \u00abEn la F\u00f3rmula 1 todo va muy r\u00e1pido: nadie me ve\u00eda como favorito al t\u00edtulo tras la primera carrera y despu\u00e9s de la segunda todos lo hacen\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. \u00abMi carrera fue algo distinta a la suya en Bar\u00e9in, pero<\/p>\n","protected":false},"author":1,"featured_media":91805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-120612","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. &quot;Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. &quot;Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-12T04:47:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-12T04:47:21+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. &quot;Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#listItem\",\"name\":\"Vettel, sin presi\\u00f3n extra ante la irrupci\\u00f3n de Leclerc\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#listItem\",\"position\":3,\"name\":\"Vettel, sin presi\\u00f3n extra ante la irrupci\\u00f3n de Leclerc\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#newsarticle\",\"name\":\"Vettel, sin presi\\u00f3n extra ante la irrupci\\u00f3n de Leclerc | Cand\\u00e1s 365\",\"headline\":\"Vettel, sin presi\\u00f3n extra ante la irrupci\\u00f3n de Leclerc\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/formula-1-630147_1280.jpg\",\"width\":1280,\"height\":851},\"datePublished\":\"2019-04-12T04:47:21+02:00\",\"dateModified\":\"2019-04-12T04:47:21+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el abril 12, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/\",\"name\":\"Vettel, sin presi\\u00f3n extra ante la irrupci\\u00f3n de Leclerc | Cand\\u00e1s 365\",\"description\":\"Shangh\\u00e1i (China), 11 abr (dpa) \\u2013 Sebastian Vettel no siente ninguna presi\\u00f3n extra en su particular duelo con su compa\\u00f1ero de equipo Charles Leclerc, reconoci\\u00f3 hoy el piloto alem\\u00e1n en una rueda de prensa de la escuder\\u00eda Ferrari previa al Gran Premio de China. \\\"Mi carrera fue algo distinta a la suya en Bar\\u00e9in, pero\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/formula-1-630147_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#mainImage\",\"width\":1280,\"height\":851},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\\\/#mainImage\"},\"datePublished\":\"2019-04-12T04:47:21+02:00\",\"dateModified\":\"2019-04-12T04:47:21+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365","description":"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. \"Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero","canonical_url":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#listItem","name":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#listItem","position":3,"name":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#newsarticle","name":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365","headline":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","width":1280,"height":851},"datePublished":"2019-04-12T04:47:21+02:00","dateModified":"2019-04-12T04:47:21+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el abril 12, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#webpage","url":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/","name":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365","description":"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. \"Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#mainImage","width":1280,"height":851},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/#mainImage"},"datePublished":"2019-04-12T04:47:21+02:00","dateModified":"2019-04-12T04:47:21+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365","og:description":"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. &quot;Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero","og:url":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","og:image:width":1280,"og:image:height":851,"article:published_time":"2019-04-12T04:47:21+00:00","article:modified_time":"2019-04-12T04:47:21+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc | Cand\u00e1s 365","twitter:description":"Shangh\u00e1i (China), 11 abr (dpa) \u2013 Sebastian Vettel no siente ninguna presi\u00f3n extra en su particular duelo con su compa\u00f1ero de equipo Charles Leclerc, reconoci\u00f3 hoy el piloto alem\u00e1n en una rueda de prensa de la escuder\u00eda Ferrari previa al Gran Premio de China. &quot;Mi carrera fue algo distinta a la suya en Bar\u00e9in, pero","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"120612","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 17:49:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:58:49","updated":"2025-08-29 17:49:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Vettel, sin presi\u00f3n extra ante la irrupci\u00f3n de Leclerc","link":"https:\/\/candas365.es\/noticias\/vettel-sin-presion-extra-ante-la-irrupcion-de-leclerc\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=120612"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/120612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91805"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=120612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=120612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=120612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}