{"id":115645,"date":"2019-02-05T20:45:24","date_gmt":"2019-02-05T20:45:24","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=115645"},"modified":"2019-02-05T20:45:24","modified_gmt":"2019-02-05T20:45:24","slug":"horoscopo-de-cancer-miercoles-6-de-febrero-2019","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/","title":{"rendered":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-115631\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s.<\/p>\n<p>Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a la gente que te quiere bien tienes que pensar en lo que ya tienes en tu vida personal y en lo que te hace feliz, no lo olvides.<\/p>\n<p>Busca respuestas para los temas que ahora mismo te hacen \u201cpensar o dudar\u201d, habla m\u00e1s con los tuyos y abre t\u00fa mente a los tiempos nuevos, feliz d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a<\/p>\n","protected":false},"author":1,"featured_media":115631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":{"0":"post-115645","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-horoscopo-diario"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"hor\u00f3scopo diario\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-05T20:45:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-05T20:45:24+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"position\":2,\"name\":\"Hor\\u00f3scopo diario\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#listItem\",\"name\":\"Hor\\u00f3scopo de C\\u00e1ncer, mi\\u00e9rcoles 6 de febrero 2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#listItem\",\"position\":3,\"name\":\"Hor\\u00f3scopo de C\\u00e1ncer, mi\\u00e9rcoles 6 de febrero 2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#newsarticle\",\"name\":\"Hor\\u00f3scopo de C\\u00e1ncer, mi\\u00e9rcoles 6 de febrero 2019 | Cand\\u00e1s 365\",\"headline\":\"Hor\\u00f3scopo de C\\u00e1ncer, mi\\u00e9rcoles 6 de febrero 2019\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/HOROSCOPO-6-FEBRERO-2019.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-02-05T20:45:24+01:00\",\"dateModified\":\"2019-02-05T20:45:24+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#webpage\"},\"articleSection\":\"Hor\\u00f3scopo diario\",\"dateline\":\"Publicado el febrero 5, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/\",\"name\":\"Hor\\u00f3scopo de C\\u00e1ncer, mi\\u00e9rcoles 6 de febrero 2019 | Cand\\u00e1s 365\",\"description\":\"Tercer d\\u00eda de la semana y buen momento para ir haciendo un peque\\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\\u00e1s. Pon m\\u00e1s amor a tu vida y presta m\\u00e1s atenci\\u00f3n a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/HOROSCOPO-6-FEBRERO-2019.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\\\/#mainImage\"},\"datePublished\":\"2019-02-05T20:45:24+01:00\",\"dateModified\":\"2019-02-05T20:45:24+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365","description":"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a","canonical_url":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/","robots":"max-image-preview:large","keywords":"hor\u00f3scopo diario","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","position":2,"name":"Hor\u00f3scopo diario","item":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#listItem","name":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#listItem","position":3,"name":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#newsarticle","name":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365","headline":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg","width":960,"height":720},"datePublished":"2019-02-05T20:45:24+01:00","dateModified":"2019-02-05T20:45:24+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#webpage"},"articleSection":"Hor\u00f3scopo diario","dateline":"Publicado el febrero 5, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#webpage","url":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/","name":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365","description":"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/#mainImage"},"datePublished":"2019-02-05T20:45:24+01:00","dateModified":"2019-02-05T20:45:24+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365","og:description":"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a","og:url":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-02-05T20:45:24+00:00","article:modified_time":"2019-02-05T20:45:24+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019 | Cand\u00e1s 365","twitter:description":"Tercer d\u00eda de la semana y buen momento para ir haciendo un peque\u00f1o balance de lo que ya has hecho y de lo que tienes por delante, hoy ser\u00e1 bueno pensar las cosas, hacer lo tuyo bien y escuchar las ideas de los dem\u00e1s. Pon m\u00e1s amor a tu vida y presta m\u00e1s atenci\u00f3n a","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/HOROSCOPO-6-FEBRERO-2019.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"115645","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 04:37:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:16:56","updated":"2025-08-29 04:37:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/\" title=\"Hor\u00f3scopo diario\">Hor\u00f3scopo diario<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tHor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Hor\u00f3scopo diario","link":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/"},{"label":"Hor\u00f3scopo de C\u00e1ncer, mi\u00e9rcoles 6 de febrero 2019","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-cancer-miercoles-6-de-febrero-2019\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=115645"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/115631"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=115645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=115645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=115645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}