{"id":115618,"date":"2019-02-05T13:36:07","date_gmt":"2019-02-05T13:36:07","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=115618"},"modified":"2019-02-05T13:36:07","modified_gmt":"2019-02-05T13:36:07","slug":"dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/","title":{"rendered":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-115619\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg 496w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa.<\/p>\n<p>La petici\u00f3n se enmarca en el art\u00edculo 9.2 del Estatuto Org\u00e1nico del Ministerio Fiscal que establece que la fiscal general del Estado \u00abinformar\u00e1 al Gobierno, cuando \u00e9ste lo interese y no exista obst\u00e1culo legal, respecto a cualquiera de los asuntos en que intervenga el Ministerio Fiscal, as\u00ed como sobre el funcionamiento, en general, de la Administraci\u00f3n de Justicia\u00bb.<\/p>\n<p>En su escrito al organismo que dirige Mar\u00eda Jos\u00e9 Segarra, la ministra Delgado recuerda que el Consejo de Ministro aprob\u00f3 en primera vuelta el pasado 28 de diciembre el Anteproyecto de Ley Org\u00e1nica de Protecci\u00f3n Integral a la Infancia y la Adolescencia frente a la Violencia \u00abcuyo objetivo es otorgar una mayor protecci\u00f3n a ni\u00f1os, ni\u00f1as y adolescentes frente a cualquier tipo de maltrato f\u00edsico, psicol\u00f3gico y emocional\u00bb.<\/p>\n<p>El documento subraya que uno de los aspectos de ese anteproyecto es la reforma de las agresiones y los abusos sexuales cometidos a menores. Esa modificaci\u00f3n cambia el r\u00e9gimen de prescripci\u00f3n de estos delitos para que el plazo empiece a contar a partir de que la v\u00edctima cumpla 30 a\u00f1os y no a los 18 como actualmente.<\/p>\n<p>Delgado justifica esos cambios por los \u00abefectos especialmente graves para el desarrollo de la personalidad de los ni\u00f1os y ni\u00f1as que los sufren, efectos que perduran durante gran parte de su vida adulta\u00bb. Tambi\u00e9n se\u00f1ala que su objetivo es \u00abgarantizar que el perjudicado o perjudicada haya alcanzado suficiente madurez para vencer la verg\u00fcenza y el miedo que generan estas execrables agresiones y pueda afrontar con solvencia la denuncia de los hechos y el proceso penal al que, en su caso, d\u00e9 lugar\u00bb.<\/p>\n<p>Por \u00faltimo, el escrito refleja c\u00f3mo, en los \u00faltimos meses, los medios de comunicaci\u00f3n han divulgado numerosos casos de supuestas agresiones sexuales cometidos en el seno de congregaciones e instituciones religiosas, instituciones que, en muchos casos, han contribuido a la ocultaci\u00f3n de esos delitos y \u00aba la protecci\u00f3n de los victimarios\u00bb.<\/p>\n<p>Esas informaciones period\u00edsticas han generado \u00abuna importante alarma social\u00bb y \u00abuna fuerte demanda para que este Gobierno aborde este fen\u00f3meno\u00bb, explica la ministra Delgado en su escrito a la fiscal general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se<\/p>\n","protected":false},"author":1,"featured_media":115619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-115618","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-05T13:36:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-05T13:36:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#listItem\",\"name\":\"Dolores Delgado reclama a la Fiscal\\u00eda informaci\\u00f3n sobre casos de agresiones sexuales de religiosos a menores\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#listItem\",\"position\":3,\"name\":\"Dolores Delgado reclama a la Fiscal\\u00eda informaci\\u00f3n sobre casos de agresiones sexuales de religiosos a menores\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#newsarticle\",\"name\":\"Dolores Delgado reclama a la Fiscal\\u00eda informaci\\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\\u00e1s 365\",\"headline\":\"Dolores Delgado reclama a la Fiscal\\u00eda informaci\\u00f3n sobre casos de agresiones sexuales de religiosos a menores\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/11062018_DoloresDelgadoArchivo.jpg\",\"width\":496,\"height\":330},\"datePublished\":\"2019-02-05T13:36:07+01:00\",\"dateModified\":\"2019-02-05T13:36:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 5, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/\",\"name\":\"Dolores Delgado reclama a la Fiscal\\u00eda informaci\\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\\u00e1s 365\",\"description\":\"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\\u00eda General del Estado que el Ministerio P\\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\\u00f3n religiosa. La petici\\u00f3n se\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/11062018_DoloresDelgadoArchivo.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#mainImage\",\"width\":496,\"height\":330},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\\\/#mainImage\"},\"datePublished\":\"2019-02-05T13:36:07+01:00\",\"dateModified\":\"2019-02-05T13:36:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365","description":"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se","canonical_url":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#listItem","name":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#listItem","position":3,"name":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#newsarticle","name":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365","headline":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg","width":496,"height":330},"datePublished":"2019-02-05T13:36:07+01:00","dateModified":"2019-02-05T13:36:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 5, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#webpage","url":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/","name":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365","description":"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg","@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#mainImage","width":496,"height":330},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/#mainImage"},"datePublished":"2019-02-05T13:36:07+01:00","dateModified":"2019-02-05T13:36:07+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365","og:description":"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se","og:url":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg","og:image:width":496,"og:image:height":330,"article:published_time":"2019-02-05T13:36:07+00:00","article:modified_time":"2019-02-05T13:36:07+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores | Cand\u00e1s 365","twitter:description":"La ministra de Justicia, Dolores Delgado, ha solicitado hoy mediante escrito enviado a la Fiscal\u00eda General del Estado que el Ministerio P\u00fablico le informe sobre las diligencias abiertas en los tribunales por agresiones y abusos sexuales a menores cometidos en el seno de congregaciones, colegios o cualquier otro tipo de instituci\u00f3n religiosa. La petici\u00f3n se","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/11062018_DoloresDelgadoArchivo.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"115618","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 04:33:37","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:16:56","updated":"2025-08-29 04:33:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Dolores Delgado reclama a la Fiscal\u00eda informaci\u00f3n sobre casos de agresiones sexuales de religiosos a menores","link":"https:\/\/candas365.es\/noticias\/dolores-delgado-reclama-a-la-fiscalia-informacion-sobre-casos-de-agresiones-sexuales-de-religiosos-a-menores\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=115618"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/115619"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=115618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=115618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=115618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}