{"id":115600,"date":"2019-02-04T21:42:27","date_gmt":"2019-02-04T21:42:27","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=115600"},"modified":"2019-02-04T21:42:27","modified_gmt":"2019-02-04T21:42:27","slug":"francia-bombardea-en-chad-una-columna-armada","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/","title":{"rendered":"Francia bombardea en Chad una \u00abcolumna armada\u00bb"},"content":{"rendered":"<figure id=\"attachment_115601\" aria-describedby=\"caption-attachment-115601\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-115601\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-1068x711.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655-631x420.jpg 631w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg 1200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-115601\" class=\"wp-caption-text\">TWITTER DE CHRISTOPHE CASTANER \/ Europa Press<\/figcaption><\/figure>\n<p>MADRID, 4 Feb. 2019 (Europa Press) &#8211;\u00a0El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una \u00abcolumna armada\u00bb integrada por cerca de 40 camionetas llegadas desde Libia y que se \u00abinfiltraron profundamente\u00bb en territorio de Chad.<\/p>\n<p>El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques fueron llevados a cabo el domingo por una patrulla de &#8216;Mirage 2000&#8217; que despegaron desde una base en la capital chadiana, Yamena.<\/p>\n<p>\u00abEsta intervenci\u00f3n, en respuesta a la demanda de las autoridades chadianas, ha ayudado a impedir ese avance hostil y dispersar la columna\u00bb, ha agregado, sin facilitar un balance sobre v\u00edctimas ni identificar a los sospechosos.<\/p>\n<p>Chad ha sido objetivo de ataques por parte de milicianos islamistas, mientras que un grupo rebelde conocido como Mando del Consejo para la Salvaci\u00f3n de la Rep\u00fablica ha llevado a cabo operaciones para intentar forzar la salida del poder, Idriss D\u00e9by.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 4 Feb. 2019 (Europa Press) &#8211;\u00a0El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una \u00abcolumna armada\u00bb integrada por cerca de 40 camionetas llegadas desde Libia y que se \u00abinfiltraron profundamente\u00bb en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques<\/p>\n","protected":false},"author":1,"featured_media":115601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-115600","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una &quot;columna armada&quot; integrada por cerca de 40 camionetas llegadas desde Libia y que se &quot;infiltraron profundamente&quot; en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una &quot;columna armada&quot; integrada por cerca de 40 camionetas llegadas desde Libia y que se &quot;infiltraron profundamente&quot; en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-04T21:42:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-04T21:42:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una &quot;columna armada&quot; integrada por cerca de 40 camionetas llegadas desde Libia y que se &quot;infiltraron profundamente&quot; en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#listItem\",\"name\":\"Francia bombardea en Chad una \\u00abcolumna armada\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#listItem\",\"position\":3,\"name\":\"Francia bombardea en Chad una \\u00abcolumna armada\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#newsarticle\",\"name\":\"Francia bombardea en Chad una \\u00abcolumna armada\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Francia bombardea en Chad una \\u00abcolumna armada\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Chad._Francia_bombar_60213655.jpg\",\"width\":1200,\"height\":799,\"caption\":\"TWITTER DE CHRISTOPHE CASTANER \\\/ Europa Press\"},\"datePublished\":\"2019-02-04T21:42:27+01:00\",\"dateModified\":\"2019-02-04T21:42:27+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 4, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/\",\"name\":\"Francia bombardea en Chad una \\u00abcolumna armada\\u00bb | Cand\\u00e1s 365\",\"description\":\"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una \\\"columna armada\\\" integrada por cerca de 40 camionetas llegadas desde Libia y que se \\\"infiltraron profundamente\\\" en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\\u00f1alado en un comunicado que los ataques\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Chad._Francia_bombar_60213655.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#mainImage\",\"width\":1200,\"height\":799,\"caption\":\"TWITTER DE CHRISTOPHE CASTANER \\\/ Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/francia-bombardea-en-chad-una-columna-armada\\\/#mainImage\"},\"datePublished\":\"2019-02-04T21:42:27+01:00\",\"dateModified\":\"2019-02-04T21:42:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365","description":"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una \"columna armada\" integrada por cerca de 40 camionetas llegadas desde Libia y que se \"infiltraron profundamente\" en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques","canonical_url":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#listItem","name":"Francia bombardea en Chad una \u00abcolumna armada\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#listItem","position":3,"name":"Francia bombardea en Chad una \u00abcolumna armada\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#newsarticle","name":"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365","headline":"Francia bombardea en Chad una \u00abcolumna armada\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg","width":1200,"height":799,"caption":"TWITTER DE CHRISTOPHE CASTANER \/ Europa Press"},"datePublished":"2019-02-04T21:42:27+01:00","dateModified":"2019-02-04T21:42:27+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 4, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#webpage","url":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/","name":"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365","description":"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una \"columna armada\" integrada por cerca de 40 camionetas llegadas desde Libia y que se \"infiltraron profundamente\" en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg","@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#mainImage","width":1200,"height":799,"caption":"TWITTER DE CHRISTOPHE CASTANER \/ Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/#mainImage"},"datePublished":"2019-02-04T21:42:27+01:00","dateModified":"2019-02-04T21:42:27+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365","og:description":"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una &quot;columna armada&quot; integrada por cerca de 40 camionetas llegadas desde Libia y que se &quot;infiltraron profundamente&quot; en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques","og:url":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg","og:image:width":1200,"og:image:height":799,"article:published_time":"2019-02-04T21:42:27+00:00","article:modified_time":"2019-02-04T21:42:27+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Francia bombardea en Chad una \u00abcolumna armada\u00bb | Cand\u00e1s 365","twitter:description":"MADRID, 4 Feb. 2019 (Europa Press) - El Ej\u00e9rcito de Francia ha anunciado este lunes una serie de bombardeos contra una &quot;columna armada&quot; integrada por cerca de 40 camionetas llegadas desde Libia y que se &quot;infiltraron profundamente&quot; en territorio de Chad. El Estado Mayor de las Fuerzas Armadas ha se\u00f1alado en un comunicado que los ataques","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/02\/Chad._Francia_bombar_60213655.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"115600","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-29 04:30:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:16:56","updated":"2025-08-29 04:30:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tFrancia bombardea en Chad una \u00abcolumna armada\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Francia bombardea en Chad una \u00abcolumna armada\u00bb","link":"https:\/\/candas365.es\/noticias\/francia-bombardea-en-chad-una-columna-armada\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=115600"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/115600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/115601"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=115600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=115600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=115600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}