{"id":1147,"date":"2014-09-23T11:44:47","date_gmt":"2014-09-23T13:44:47","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=1147"},"modified":"2014-09-23T11:44:47","modified_gmt":"2014-09-23T13:44:47","slug":"un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/","title":{"rendered":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques"},"content":{"rendered":"<p>OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques.<\/p>\n<p>La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director del Agadic, Jacobo Sutil, el gerente del Auditorio de Galicia, Jos\u00e9 V\u00edctor Carou, y el director del festival, Jorge Rey.<\/p>\n<p>El festival este a\u00f1o estar\u00e1 compuesto por 25 espect\u00e1culos y cuatro funciones de microteatro, adem\u00e1s de funciones escolares, y en \u00e9l participar\u00e1n compa\u00f1\u00edas de Rusia, B\u00e9lgica, Brasil, Argentina e Inglaterra, as\u00ed como de diferentes puntos de Espa\u00f1a, como Euskadi, Catalu\u00f1a, Arag\u00f3n, Asturias, Valencia, Madrid o Castilla la Mancha, adem\u00e1s de Galicia.<\/p>\n<p>Como es tradicional, los espect\u00e1culos se celebrar\u00e1n en distintos espacios de la ciudad, entre los que se encuentran el Teatro Principal, la Zona C, la Fundaci\u00f3n Sgae, la Alameda, A Regadeira de Adela y las plazas de Toural, San Marti\u00f1o Pinario y Praza Roxa.<\/p>\n<p>Entre la programaci\u00f3n, que contar\u00e1 con piezas para ni\u00f1os y para adultos, Mar\u00eda Ant\u00f3n ha destacado el estreno mundial del espect\u00e1culo &#8216;Habla, no est\u00e1s sola&#8217;, de la compa\u00f1\u00eda La Mar de Marionetas; o la funci\u00f3n inaugural de Galicreques con &#8216;La danza de las marionetas&#8217;, de Plansjet (B\u00e9lgica), galardonados en la actual edici\u00f3n por su trayectoria.<\/p>\n<p>Paralelamente, varios espect\u00e1culos \u00absorprender\u00e1n por su cuidada puesta en escena\u00bb, como &#8216;Circus on the strings&#8217;, del ruso Viktor Antonov; o &#8216;Mozart preposteroso&#8217;, de la artista inglesa Nola Rae, que pondr\u00e1 cierre al festival.<\/p>\n<p>Galicreques 2014 organizar\u00e1 una gala especial con la participaci\u00f3n de los artistas presentes en el festival que buscar\u00e1 ser una \u00abnoche de uni\u00f3n\u00bb entre palestinos e israel\u00edes, ha apuntado Mar\u00eda Ant\u00f3n, en la que se \u00abreivindique la paz\u00bb. La iniciativa, en colaboraci\u00f3n con la Fundaci\u00f3n Araguaney, destinar\u00e1 la recaudaci\u00f3n de la gala a la compra y env\u00edo de medicamentos a Gaza.<\/p>\n<p>OTRAS ACTIVIDADES<\/p>\n<p>Adem\u00e1s de espect\u00e1culos, el festival completar\u00e1 su programaci\u00f3n con charlas y mesas redondas, as\u00ed como talleres de construcci\u00f3n, funciones escolares y dos exposiciones.<\/p>\n<p>En esta l\u00ednea, los asistentes podr\u00e1n ver &#8216;T\u00edteres de \u00c1frica&#8217; en la Fundaci\u00f3n Sgae y &#8216;Humor con los t\u00edteres. Ilustraciones de Miguel Oyarz\u00fan&#8217;, que se expondr\u00e1 en el Centro Socio Cultural del Ensanche. Las funciones escolares, a cargo de 10 compa\u00f1\u00edas, se celebrar\u00e1n desde el 29 de septiembre al 3 de octubre.<\/p>\n<p>Jos\u00e9 V\u00edctor Carou ha confirmado que las entradas para este festival est\u00e1n ya a la venta en la taquilla del Teatro Principal a un precio de cinco euros, con descuentos familiares. Para los espect\u00e1culos en la Zona C y en la Fundaci\u00f3n Sgae, las entradas pueden adquirirse tambi\u00e9n en estos espacios antes de las funciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director<\/p>\n","protected":false},"author":1,"featured_media":270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1147","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-09-23T13:44:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-09-23T13:44:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#listItem\",\"name\":\"Un total de 21 compa\\u00f1\\u00edas participar\\u00e1n en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#listItem\",\"position\":3,\"name\":\"Un total de 21 compa\\u00f1\\u00edas participar\\u00e1n en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#newsarticle\",\"name\":\"Un total de 21 compa\\u00f1\\u00edas participar\\u00e1n en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques | Cand\\u00e1s 365\",\"headline\":\"Un total de 21 compa\\u00f1\\u00edas participar\\u00e1n en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"width\":500,\"height\":331},\"datePublished\":\"2014-09-23T11:44:47+02:00\",\"dateModified\":\"2014-09-23T11:44:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el septiembre 23, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/\",\"name\":\"Un total de 21 compa\\u00f1\\u00edas participar\\u00e1n en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques | Cand\\u00e1s 365\",\"description\":\"OVIEDO\\\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\\u00f1\\u00edas procedentes de distintos pa\\u00edses participar\\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\\u00eda Ant\\u00f3n, ha presentado este martes el festival en compa\\u00f1\\u00eda del director\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#mainImage\",\"width\":500,\"height\":331},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\\\/#mainImage\"},\"datePublished\":\"2014-09-23T11:44:47+02:00\",\"dateModified\":\"2014-09-23T11:44:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365","description":"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director","canonical_url":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#listItem","name":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#listItem","position":3,"name":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#newsarticle","name":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365","headline":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","width":500,"height":331},"datePublished":"2014-09-23T11:44:47+02:00","dateModified":"2014-09-23T11:44:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el septiembre 23, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#webpage","url":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/","name":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365","description":"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#mainImage","width":500,"height":331},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/#mainImage"},"datePublished":"2014-09-23T11:44:47+02:00","dateModified":"2014-09-23T11:44:47+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365","og:description":"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director","og:url":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:width":500,"og:image:height":331,"article:published_time":"2014-09-23T13:44:47+00:00","article:modified_time":"2014-09-23T13:44:47+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques | Cand\u00e1s 365","twitter:description":"OVIEDO\/SANTIAGO DE COMPOSTELA, 23 Sep. (EUROPA PRESS) Un total de 21 compa\u00f1\u00edas procedentes de distintos pa\u00edses participar\u00e1n entre el 27 de septiembre y el 5 de octubre en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques. La concejala de Cultura de Santiago, Mar\u00eda Ant\u00f3n, ha presentado este martes el festival en compa\u00f1\u00eda del director","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"1147","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 23:21:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:39:16","updated":"2026-05-12 23:21:19","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUn total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"Un total de 21 compa\u00f1\u00edas participar\u00e1n en Santiago en el XIX Festival Internacional de T\u00edteres Galicreques","link":"https:\/\/candas365.es\/noticias\/un-total-de-21-companias-participaran-en-santiago-en-el-xix-festival-internacional-de-titeres-galicreques\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=1147"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/1147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=1147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=1147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}