{"id":1141,"date":"2014-09-23T11:40:39","date_gmt":"2014-09-23T13:40:39","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=1141"},"modified":"2014-09-23T11:40:39","modified_gmt":"2014-09-23T13:40:39","slug":"emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/","title":{"rendered":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo"},"content":{"rendered":"<p>MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo.<\/p>\n<p>En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates y obtener una visi\u00f3n interna de la compa\u00f1\u00eda y de c\u00f3mo es trabajar en ella.<\/p>\n<p>Emirates busca empleados comprometidos, abiertos de miras, serviciales y amables. Los candidatos deben ser mayores de 21 a\u00f1os en la fecha de la posible selecci\u00f3n y deben presentar un curriculum vitae actualizado en ingl\u00e9s as\u00ed como una fotograf\u00eda.<\/p>\n<p>Antes de la jornada de puertas abiertas los candidatos deben registrarse &#8216;online&#8217;, donde tambi\u00e9n pueden encontrar m\u00e1s informaci\u00f3n acerca de las posibilidades de desarrollar una carrera profesional en Emirates.<\/p>\n<p>En esta ocasi\u00f3n, solo los candidatos que hayan sido invitados previamente podr\u00e1n acceder a las jornadas de Madrid y Barcelona, mientras que en Oviedo se tratar\u00e1 de una Jornada de Puertas Abiertas para todos los interesados en entrar en el proceso de selecci\u00f3n.<\/p>\n<p>Los aspirantes que deseen poder recibir una invitaci\u00f3n a las citas de las capitales espa\u00f1ola y catalana deben inscribirse antes de los d\u00edas 11 y 12 de octubre en la web de la compa\u00f1\u00eda para que el personal de Emirates pueda valorar su perfil y extender la invitaci\u00f3n si procede.<\/p>\n<p>R\u00c1PIDA EXPANSI\u00d3N<\/p>\n<p>Actualmente Emirates sirve 145 ciudades en todo el mundo con una flota joven y tecnol\u00f3gicamente avanzada de 228 aviones de fuselaje ancho, equipados con las comodidades m\u00e1s punteras de la industria. Adem\u00e1s, Emirates tiene encargados otros 215 aviones de fuselaje ancho y es el principal cliente del Airbus 380 con 52 aeronaves ya en su flota y otras 88 pendientes de entrega.<\/p>\n<p>Dada su r\u00e1pida y din\u00e1mica expansi\u00f3n, Emirates busca incorporar a 3.000 tripulantes de cabina este a\u00f1o. Emirates ofrece varios puestos de trabajo a bordo de sus aviones, en los que trabaja un equipo de personas internacional compuesto por m\u00e1s de 16.000 asistentes de vuelo procedentes de m\u00e1s de 120 pa\u00edses que se comunican en m\u00e1s de 50 idiomas.<\/p>\n<p>En la actualidad, Emirates cuenta con m\u00e1s de 100 pilotos y m\u00e1s de 375 tripulantes de cabina espa\u00f1oles, y cada a\u00f1o recluta a m\u00e1s candidatos a trav\u00e9s de varios programas de selecci\u00f3n en ciudades espa\u00f1olas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates<\/p>\n","protected":false},"author":1,"featured_media":1142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1141","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-09-23T13:40:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-09-23T13:40:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#listItem\",\"name\":\"Emirates seleccionar\\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#listItem\",\"position\":3,\"name\":\"Emirates seleccionar\\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#newsarticle\",\"name\":\"Emirates seleccionar\\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\\u00e1s 365\",\"headline\":\"Emirates seleccionar\\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/fotonoticia_20140923140533_800.jpg\",\"width\":800,\"height\":577},\"datePublished\":\"2014-09-23T11:40:39+02:00\",\"dateModified\":\"2014-09-23T11:40:39+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el septiembre 23, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/\",\"name\":\"Emirates seleccionar\\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\\u00e1s 365\",\"description\":\"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\\u00e1 una serie de jornadas informativas para la selecci\\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\\u00e1n conversar con el equipo de selecci\\u00f3n de Emirates\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/fotonoticia_20140923140533_800.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#mainImage\",\"width\":800,\"height\":577},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\\\/#mainImage\"},\"datePublished\":\"2014-09-23T11:40:39+02:00\",\"dateModified\":\"2014-09-23T11:40:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365","description":"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates","canonical_url":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#listItem","name":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#listItem","position":3,"name":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#newsarticle","name":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365","headline":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg","width":800,"height":577},"datePublished":"2014-09-23T11:40:39+02:00","dateModified":"2014-09-23T11:40:39+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el septiembre 23, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#webpage","url":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/","name":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365","description":"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg","@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#mainImage","width":800,"height":577},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/#mainImage"},"datePublished":"2014-09-23T11:40:39+02:00","dateModified":"2014-09-23T11:40:39+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365","og:description":"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates","og:url":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg","og:image:width":800,"og:image:height":577,"article:published_time":"2014-09-23T13:40:39+00:00","article:modified_time":"2014-09-23T13:40:39+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo | Cand\u00e1s 365","twitter:description":"MADRID, 23 Sep. (EUROPA PRESS) Emirates Airline celebrar\u00e1 una serie de jornadas informativas para la selecci\u00f3n de tripulantes de cabina el 11 de octubre en Barcelona, el 12 en Madrid y el 17 de octubre en Oviedo. En las jornadas informativas, los hombres y mujeres interesados podr\u00e1n conversar con el equipo de selecci\u00f3n de Emirates","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/fotonoticia_20140923140533_800.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"1141","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 23:21:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:39:16","updated":"2026-05-12 23:21:17","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEmirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"Emirates seleccionar\u00e1 tripulantes de cabina en Barcelona, Madrid y Oviedo","link":"https:\/\/candas365.es\/noticias\/emirates-seleccionara-tripulantes-de-cabina-en-barcelona-madrid-y-oviedo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/1141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=1141"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/1141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/1142"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=1141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=1141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=1141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}