{"id":110983,"date":"2018-11-29T21:29:39","date_gmt":"2018-11-29T21:29:39","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=110983"},"modified":"2018-11-29T21:29:39","modified_gmt":"2018-11-29T21:29:39","slug":"horoscopo-de-libra-viernes-30-de-noviembre-2018","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/","title":{"rendered":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-110977\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti.<\/p>\n<p>Cuida de tu salud y evita cualquier tipo de exceso tanto en el d\u00eda como en la noche, no malgastes dinero ni energ\u00edas en algo que no sea bueno o en algo que no te aporte beneficios reales.<\/p>\n<p>Lo mejor del viernes ser\u00e1 el amor y la amistad, lo m\u00e1s complicado quiz\u00e1s sea distribuir t\u00fa tiempo para poder hacer todo lo que ahora mismo te apetece, piensa con calma y disfruta del d\u00eda, suerte \u00a1!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y<\/p>\n","protected":false},"author":1,"featured_media":110977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-110983","post","type-post","status-publish","format-standard","has-post-thumbnail","category-horoscopo-diario"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"hor\u00f3scopo diario\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-29T21:29:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-29T21:29:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"position\":2,\"name\":\"Hor\\u00f3scopo diario\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#listItem\",\"name\":\"Hor\\u00f3scopo de Libra, viernes 30 de noviembre 2018\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#listItem\",\"position\":3,\"name\":\"Hor\\u00f3scopo de Libra, viernes 30 de noviembre 2018\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#newsarticle\",\"name\":\"Hor\\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\\u00e1s 365\",\"headline\":\"Hor\\u00f3scopo de Libra, viernes 30 de noviembre 2018\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/HOROSCOPO-30-noviembre-2018.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2018-11-29T21:29:39+01:00\",\"dateModified\":\"2018-11-29T21:29:39+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#webpage\"},\"articleSection\":\"Hor\\u00f3scopo diario\",\"dateline\":\"Publicado el noviembre 29, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/\",\"name\":\"Hor\\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\\u00e1s 365\",\"description\":\"El amor tendr\\u00e1 mucho protagonismo hoy viernes en tu vida, ser\\u00e1 ese motor que mover\\u00e1 tu mundo y lo que te ayudar\\u00e1 a confiar y a creer m\\u00e1s en los dem\\u00e1s, pero tambi\\u00e9n ser\\u00e1 lo que te har\\u00e1 ver cosas que no esperas y que pueden ser \\u201cbonitas\\u201d para ti. Cuida de tu salud y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/HOROSCOPO-30-noviembre-2018.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-viernes-30-de-noviembre-2018\\\/#mainImage\"},\"datePublished\":\"2018-11-29T21:29:39+01:00\",\"dateModified\":\"2018-11-29T21:29:39+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365","description":"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y","canonical_url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/","robots":"max-image-preview:large","keywords":"hor\u00f3scopo diario","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","position":2,"name":"Hor\u00f3scopo diario","item":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#listItem","name":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#listItem","position":3,"name":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#newsarticle","name":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365","headline":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg","width":960,"height":720},"datePublished":"2018-11-29T21:29:39+01:00","dateModified":"2018-11-29T21:29:39+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#webpage"},"articleSection":"Hor\u00f3scopo diario","dateline":"Publicado el noviembre 29, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#webpage","url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/","name":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365","description":"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/#mainImage"},"datePublished":"2018-11-29T21:29:39+01:00","dateModified":"2018-11-29T21:29:39+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365","og:description":"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y","og:url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2018-11-29T21:29:39+00:00","article:modified_time":"2018-11-29T21:29:39+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018 | Cand\u00e1s 365","twitter:description":"El amor tendr\u00e1 mucho protagonismo hoy viernes en tu vida, ser\u00e1 ese motor que mover\u00e1 tu mundo y lo que te ayudar\u00e1 a confiar y a creer m\u00e1s en los dem\u00e1s, pero tambi\u00e9n ser\u00e1 lo que te har\u00e1 ver cosas que no esperas y que pueden ser \u201cbonitas\u201d para ti. Cuida de tu salud y","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/HOROSCOPO-30-noviembre-2018.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"110983","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-22 19:57:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:38:05","updated":"2026-05-22 19:57:27","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/\" title=\"Hor\u00f3scopo diario\">Hor\u00f3scopo diario<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tHor\u00f3scopo de Libra, viernes 30 de noviembre 2018\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Hor\u00f3scopo diario","link":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/"},{"label":"Hor\u00f3scopo de Libra, viernes 30 de noviembre 2018","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-viernes-30-de-noviembre-2018\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/110983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=110983"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/110983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/110977"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=110983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=110983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=110983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}