{"id":110784,"date":"2018-11-27T03:12:58","date_gmt":"2018-11-27T03:12:58","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=110784"},"modified":"2018-11-27T03:12:58","modified_gmt":"2018-11-27T03:12:58","slug":"juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/","title":{"rendered":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" class=\"alignleft size-medium wp-image-95195\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/old-books-436498_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Guadalajara (M\u00e9xico), 26 nov (dpa) &#8211; El mexicano Juan Villoro asegur\u00f3 que \u00ab\u00e9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en \u00abtiempos de creciente intolerancia\u00bb en el mundo.<\/p>\n<p>\u00abMe parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede ser tan caprichoso como le da la gana y tan mala persona como quiera, y al mismo tiempo escribir buenas novelas. El periodista no lo puede hacer porque ya estar\u00eda negando su compromiso con la verdad, con la objetividad, con los dem\u00e1s\u00bb, manifest\u00f3 Villoro en una entrevista con dpa.<\/p>\n<p>El mexicano present\u00f3 este domingo en la Feria Internacional del Libro de Guadalajara su \u00faltimo libro, \u00abEl V\u00e9rtigo Horizontal\u00bb, un \u00abhomenaje cr\u00edtico\u00bb a la Ciudad de M\u00e9xico, donde naci\u00f3 hace 62 a\u00f1os, que combina cr\u00f3nicas, reportajes y su particular mirada de la capital del pa\u00eds.<\/p>\n<p>dpa: \u00bfSe considera periodista?<\/p>\n<p>Villoro: No s\u00e9 si estoy usurpando funciones. He hecho reportajes puros y duros, de hecho en \u00abEl V\u00e9rtigo Horizontal\u00bb hay algunos textos que considero m\u00e1s period\u00edsticos, aquellos donde hab\u00eda realidades ajenas a m\u00ed que yo tuve que cubrir m\u00e1s como reportero.<\/p>\n<p>Tambi\u00e9n he hecho entrevistas con el af\u00e1n de ser periodista, pero tambi\u00e9n tratando de mantener en ellas cierto impulso narrativo. Durante muchos a\u00f1os, cuando me preguntaban mi profesi\u00f3n yo respond\u00eda periodista, porque me parec\u00eda pretencioso llamarme escritor. Me gusta m\u00e1s la humildad del periodismo, en la medida en que es un g\u00e9nero en el que es importante que sean los dem\u00e1s los que tengan la raz\u00f3n y que sea la realidad la que te dicte los asuntos.<\/p>\n<p>dpa: \u00bfDir\u00eda que el periodismo es como nunca un pilar de la sociedad?<\/p>\n<p>Villoro: Vivimos en tiempos de una creciente intolerancia, no s\u00f3lo en M\u00e9xico sino en todo el mundo, si vemos la relaci\u00f3n de (Donald) Trump con la prensa, si vemos la importancia de las noticias falsas en redes sociales, si vemos los autoritarismos creciendo en Brasil, Hungr\u00eda, Polonia, Italia. Son momentos dif\u00edciles, pero precisamente la amenaza al periodismo refrenda su importancia, es una paradoja, si no quieren que se digan cosas es por algo, tenemos que decirlas encontrando la manera de hacerlo.<\/p>\n<p>dpa: Tambi\u00e9n es un momento importante para los movimientos feministas, \u00bfhay un ajuste de cuentas con el g\u00e9nero femenino en el \u00e1mbito literario?<\/p>\n<p>Villoro: No dir\u00eda que es un ajuste de cuentas, lo veo como un reconocimiento necesario de una realidad que tenemos, y es que hay extraordinarias escritoras y no s\u00f3lo escritoras sino mujeres que en todos los campos est\u00e1n destacando. Desgraciadamente vivimos en una sociedad patriarcal, entonces es muy dif\u00edcil que tengan la visibilidad que merecen, pero ata\u00f1e a todos los campos, cada quien en su propio espacio tiene que luchar para que esto cambie.<\/p>\n<p>dpa: Usted es miembro del Colegio Nacional de M\u00e9xico, cuyo cuerpo acad\u00e9mico se destaca por la falta de mujeres.<\/p>\n<p>Villoro: Tradicionalmente el Colegio Nacional no ha tenido muchas voces de mujeres. Naci\u00f3 a principios del siglo XX con 20 hombres. En los a\u00f1os 70 se duplic\u00f3 y pas\u00f3 a tener 40 hombres. Cuando yo ingres\u00e9 hace cuatro a\u00f1os hab\u00eda s\u00f3lo dos mujeres. Ahora tenemos cinco, lo cual har\u00eda pensar que si seguimos con la tendencia renovadora en otros cuatro a\u00f1os habr\u00e1 12 y en cuatro a\u00f1os ser\u00e1n mayor\u00eda las mujeres, ojal\u00e1 as\u00ed suceda, estamos tratando, pero es importante que se haga en todos los frentes.<\/p>\n<p>dpa: El tema de su nuevo libro vuelve a insistir en una de sus obsesiones, la Ciudad de M\u00e9xico, \u00bfpor qu\u00e9 elige volver siempre a ella?<\/p>\n<p>Villoro: Es un homenaje cr\u00edtico, porque toda ciudad, especialmente la de M\u00e9xico, te despierta emociones encontradas. Muchas veces he querido abandonarla, pero es como ciertas relaciones amorosas en donde piensas que no puedes seguir ya con esa persona y luego consideras que la extra\u00f1ar\u00edas demasiado si te fueras. La Ciudad de M\u00e9xico genera esta relaci\u00f3n de amor\/odio continua y el libro es producto de eso, quiz\u00e1s predomina m\u00e1s el amor, porque finalmente me he quedado en la ciudad y es el \u00fanico sitio que considero m\u00edo.<\/p>\n<p>dpa: \u00bfLe cost\u00f3 finalizar \u00abEl V\u00e9rtigo Horizontal\u00bb?<\/p>\n<p>Villoro: S\u00ed, uno de los grandes problemas de escribir sobre un tema tan amplio es caer en la din\u00e1mica de lo exhaustivo, tratar de ser enciclop\u00e9dico. De alguna manera se volvi\u00f3 una expansi\u00f3n avasallante que ten\u00eda que controlar de alguna forma. De broma dec\u00eda que, m\u00e1s que un corrector de estilo, necesitaba un urbanista que lo estructurara.<\/p>\n<p>dpa: \u00bfC\u00f3mo escribi\u00f3 el poema que cierra el libro, que ya se hab\u00eda publicado unos d\u00edas despu\u00e9s del terremoto que sacudi\u00f3 la Ciudad de M\u00e9xico el 19 de septiembre de 2017 y que dej\u00f3 unos 228 muertos en la capital?<\/p>\n<p>Villoro: Fue producto de la urgencia period\u00edstica, el terremoto ocurri\u00f3 un martes y ten\u00eda que entregar mi columna un jueves. A dos d\u00edas de distancia de la tragedia no pod\u00eda pensar en otra cosa, al mismo tiempo no ten\u00eda nada nuevo qu\u00e9 decir. Se me ocurri\u00f3 tratar de describir el gesto que me parec\u00eda m\u00e1s importante aquellos d\u00edas, el de levantar el pu\u00f1o para que los dem\u00e1s guardaran silencio y se pudiera escuchar si hab\u00eda gente con vida entre los escombros.<\/p>\n<p>Este gesto solidario de darle prioridad al menos favorecido era lo que estaba determinando las jornadas y yo sent\u00eda que hab\u00eda una poderosa fuerza simb\u00f3lica en todo eso. Para volcar la emoci\u00f3n pod\u00eda acudir al g\u00e9nero de la letan\u00eda, poniendo al lector como protagonista y habl\u00e1ndole de t\u00fa. Me quedaban dos horas para el cierre, as\u00ed lo escrib\u00ed, no sab\u00eda la extensi\u00f3n, porque no puedes calcular por l\u00edneas, lo ajustamos con los editores, y m\u00e1s que un g\u00e9nero literario respondi\u00f3 a uno sismol\u00f3gico: es una r\u00e9plica.<\/p>\n<p>Quiz\u00e1s por eso mismo pude decir cosas que no sab\u00eda que pod\u00edan conectar con la gente, tuvo una acogida sorprendente para m\u00ed y ya no es m\u00edo, siento que todo el mundo se lo apropi\u00f3 y me pareci\u00f3 el punto final correcto para este libro que amenazaba con no tener nunca un punto final.<\/p>\n<p>dpa: \u00bfVolver\u00e1 a escribir poes\u00eda?<\/p>\n<p>Villoro: No me considero poeta, no considero tener esa capacidad de s\u00edntesis, quiz\u00e1s necesitar\u00e9 de otro predicamento tan grande como el terremoto para que salga otro poema, yo no s\u00e9 siquiera si es un poema, no me he preguntado al respecto.<\/p>\n<p>JUAN VILLORO (Ciudad de M\u00e9xico, 1956) es escritor, periodista y profesor de literatura. En 2004 fue galardonado con el Premio Herralde por su novela \u00abEl testigo\u00bb. Tambi\u00e9n ha trabajado en el teatro, ha sido guionista de cine y ha escrito relatos de viaje.<\/p>\n<p>Por Manuel Gonz\u00e1lez Vargas (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guadalajara (M\u00e9xico), 26 nov (dpa) &#8211; El mexicano Juan Villoro asegur\u00f3 que \u00ab\u00e9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en \u00abtiempos de creciente intolerancia\u00bb en el mundo. \u00abMe parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede<\/p>\n","protected":false},"author":1,"featured_media":94892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"class_list":{"0":"post-110784","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociedad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que &quot;\u00e9ticamente es m\u00e1s valioso ser periodista que escritor&quot; al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en &quot;tiempos de creciente intolerancia&quot; en el mundo. &quot;Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que &quot;\u00e9ticamente es m\u00e1s valioso ser periodista que escritor&quot; al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en &quot;tiempos de creciente intolerancia&quot; en el mundo. &quot;Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-27T03:12:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-27T03:12:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que &quot;\u00e9ticamente es m\u00e1s valioso ser periodista que escritor&quot; al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en &quot;tiempos de creciente intolerancia&quot; en el mundo. &quot;Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#listItem\",\"name\":\"Juan Villoro: \\u00ab\\u00c9ticamente es m\\u00e1s valioso ser periodista que escritor\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#listItem\",\"position\":3,\"name\":\"Juan Villoro: \\u00ab\\u00c9ticamente es m\\u00e1s valioso ser periodista que escritor\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#newsarticle\",\"name\":\"Juan Villoro: \\u00ab\\u00c9ticamente es m\\u00e1s valioso ser periodista que escritor\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Juan Villoro: \\u00ab\\u00c9ticamente es m\\u00e1s valioso ser periodista que escritor\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/book-759873_1920.jpg\",\"width\":1920,\"height\":1170},\"datePublished\":\"2018-11-27T03:12:58+01:00\",\"dateModified\":\"2018-11-27T03:12:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#webpage\"},\"articleSection\":\"Sociedad\",\"dateline\":\"Publicado el noviembre 27, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/\",\"name\":\"Juan Villoro: \\u00ab\\u00c9ticamente es m\\u00e1s valioso ser periodista que escritor\\u00bb | Cand\\u00e1s 365\",\"description\":\"Guadalajara (M\\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\\u00f3 que \\\"\\u00e9ticamente es m\\u00e1s valioso ser periodista que escritor\\\" al evaluar sus dos profesiones, adem\\u00e1s de defender la importancia del oficio period\\u00edstico en \\\"tiempos de creciente intolerancia\\\" en el mundo. \\\"Me parece que \\u00e9ticamente es m\\u00e1s valioso ser periodista que escritor. Un escritor puede\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/book-759873_1920.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#mainImage\",\"width\":1920,\"height\":1170},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\\\/#mainImage\"},\"datePublished\":\"2018-11-27T03:12:58+01:00\",\"dateModified\":\"2018-11-27T03:12:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365","description":"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que \"\u00e9ticamente es m\u00e1s valioso ser periodista que escritor\" al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en \"tiempos de creciente intolerancia\" en el mundo. \"Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede","canonical_url":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/candas365.es\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#listItem","name":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#listItem","position":3,"name":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#newsarticle","name":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365","headline":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg","width":1920,"height":1170},"datePublished":"2018-11-27T03:12:58+01:00","dateModified":"2018-11-27T03:12:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#webpage"},"articleSection":"Sociedad","dateline":"Publicado el noviembre 27, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#webpage","url":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/","name":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365","description":"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que \"\u00e9ticamente es m\u00e1s valioso ser periodista que escritor\" al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en \"tiempos de creciente intolerancia\" en el mundo. \"Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg","@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#mainImage","width":1920,"height":1170},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/#mainImage"},"datePublished":"2018-11-27T03:12:58+01:00","dateModified":"2018-11-27T03:12:58+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365","og:description":"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que &quot;\u00e9ticamente es m\u00e1s valioso ser periodista que escritor&quot; al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en &quot;tiempos de creciente intolerancia&quot; en el mundo. &quot;Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede","og:url":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg","og:image:width":1920,"og:image:height":1170,"article:published_time":"2018-11-27T03:12:58+00:00","article:modified_time":"2018-11-27T03:12:58+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb | Cand\u00e1s 365","twitter:description":"Guadalajara (M\u00e9xico), 26 nov (dpa) - El mexicano Juan Villoro asegur\u00f3 que &quot;\u00e9ticamente es m\u00e1s valioso ser periodista que escritor&quot; al evaluar sus dos profesiones, adem\u00e1s de defender la importancia del oficio period\u00edstico en &quot;tiempos de creciente intolerancia&quot; en el mundo. &quot;Me parece que \u00e9ticamente es m\u00e1s valioso ser periodista que escritor. Un escritor puede","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/book-759873_1920.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"6 minutos"},"aioseo_meta_data":{"post_id":"110784","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-28 13:35:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:47:14","updated":"2025-08-28 13:35:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tJuan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Sociedad","link":"https:\/\/candas365.es\/noticias\/category\/sociedad\/"},{"label":"Juan Villoro: \u00ab\u00c9ticamente es m\u00e1s valioso ser periodista que escritor\u00bb","link":"https:\/\/candas365.es\/noticias\/juan-villoro-eticamente-es-mas-valioso-ser-periodista-que-escritor\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/110784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=110784"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/110784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/94892"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=110784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=110784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=110784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}