{"id":104126,"date":"2018-08-31T18:06:45","date_gmt":"2018-08-31T18:06:45","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=104126"},"modified":"2018-08-31T18:06:45","modified_gmt":"2018-08-31T18:06:45","slug":"grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/","title":{"rendered":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-104127\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg 496w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su \u00abcompromiso constante\u00bb en la lucha contra la inmigraci\u00f3n irregular\u00bb, y a los que ha garantizado el soporte espa\u00f1ol en el control de las fronteras de aquel pa\u00eds.<\/p>\n<p>Grande-Marlaska ha defendido el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de las relaciones bilaterales y ha subrayado \u00abla excelencia\u00bb de sus resultados: desde 2009 tan solo han llegado a las costas canarias cuatro embarcaciones procedentes de Senegal. No obstante, el titular de Interior ha advertido de la preocupaci\u00f3n \u00abmutua\u00bb relacionada con la b\u00fasqueda de nuevas rutas de los grupos que hasta hace poco operaban en el Mediterr\u00e1neo central.<\/p>\n<p>\u00abLa mejor f\u00f3rmula para luchar contra la inmigraci\u00f3n irregular y contra las redes de tr\u00e1fico de personas es la prevenci\u00f3n en origen y la cooperaci\u00f3n\u00bb, ha defendido Grande-Marlaska que ha asegurado que el modelo hispano-senegal\u00e9s es admirado en el resto de la Uni\u00f3n Europea y que Espa\u00f1a \u00abes y quiere seguir siendo el puente entre Dakar y Bruselas\u00bb.<\/p>\n<p>En este contexto, Grande-Marlaska ha apostado por continuar con \u00ablos esfuerzos conjuntos\u00bb que ahora est\u00e1n centrados en los proyectos Blue-Sahel y GARSI-Sahel, dos iniciativas de la UE, de concepci\u00f3n espa\u00f1ola, que -seg\u00fan el ministro- ser\u00e1n \u00abdecisivas\u00bb para las Fuerzas y Cuerpos de Seguridad de Senegal en la gesti\u00f3n de las fronteras a\u00e9reas, mar\u00edtimas y terrestres y en la lucha contra las diversas amenazas a la seguridad.<\/p>\n<p><strong>Lucha contra el terrorismo yihadista<\/strong><\/p>\n<p>El ministro del Interior espa\u00f1ol ha remarcado tambi\u00e9n la \u00abpreocupaci\u00f3n mutua\u00bb de Espa\u00f1a y Senegal por la amenaza que supone el terrorismo yihadista y ha expresado su determinaci\u00f3n y voluntad con un \u00abtrabajo conjunto que ha mejorado y ha adquirido una mayor entidad en los \u00faltimos a\u00f1os\u00bb.<\/p>\n<p>Grande-Marlaska ha puesto como ejemplo de cooperaci\u00f3n antiterrorista hispano-senegalesa, la creaci\u00f3n de una Unidad tipo GAR de la Gendarmer\u00eda Nacional Senegalesa en 2012; una experiencia que sirvi\u00f3 como modelo para el Proyecto GARSI-Sahel.<\/p>\n<p>Otra cuestiones fundamentales de ese trabajo conjunto son la faceta formativa, que ha permitido que miembros de las Fuerzas de Seguridad de Senegal hayan participado en cursos especializados sobre materia antiterrorista impartidos en Espa\u00f1a, y el intercambio de informaci\u00f3n entre ambos pa\u00edses con instrumentos como el Protocolo de Colaboraci\u00f3n entre el Centro de Inteligencia contra el Terrorismo y el Crimen Organizado (CITCO) espa\u00f1ol y la Direcci\u00f3n de Inteligencia nacional (DNR) senegalesa.<\/p>\n<p>En este viaje, Grande-Marlaska se ha reunido primero con el ministro del Interior y de Seguridad P\u00fablica, Aly Ngouille Ndiaye. A media tarde ha visitado los dispositivos de vigilancia mar\u00edtima de Senegal y Espa\u00f1a (Polic\u00eda Nacional y Guardia Civil) en el puerto de Dakar. Por \u00faltimo se ha desplazado al Palacio Presidencial donde se ha reunido con el Presidente de la Rep\u00fablica de Senegal, Macky Sall.<\/p>\n<p>Durante estos encuentros, tambi\u00e9n han tratado asuntos relacionados con la lucha contra el crimen organizado y el narcotr\u00e1fico y ha subrayado el intercambio de informaci\u00f3n estrat\u00e9gica que, por ejemplo, el mes pasado permiti\u00f3 detener en Senegal a un preso fugado de El Dueso cuando disfrutaba de un permiso penitenciario.<\/p>\n<p>Este es el quinto viaje internacional que realiza Grande-Marlaska desde que fue nombrado ministro del Interior, y todos ellos han tenido a la pol\u00edtica migratoria como uno de sus principales ejes. Adem\u00e1s de la participaci\u00f3n en el Consejo de Justicia y Asuntos de Interior (JAI) de la Uni\u00f3n Europea en Innsbruck (Austria), en el que el tema migratorio tuvo un gran peso, Grande-Marlaska ha visitado ya Marruecos, Argelia y Mauritania, en l\u00ednea con la apuesta del Gobierno por reforzar la cooperaci\u00f3n con los pa\u00edses de origen y de tr\u00e1nsito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su \u00abcompromiso constante\u00bb en la lucha contra la inmigraci\u00f3n irregular\u00bb, y a los que ha garantizado el soporte espa\u00f1ol en el control<\/p>\n","protected":false},"author":1,"featured_media":104127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-104126","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su &quot;compromiso constante&quot; en la lucha contra la inmigraci\u00f3n irregular&quot;, y a los que ha garantizado el soporte espa\u00f1ol en el control\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su &quot;compromiso constante&quot; en la lucha contra la inmigraci\u00f3n irregular&quot;, y a los que ha garantizado el soporte espa\u00f1ol en el control\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-08-31T18:06:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-08-31T18:06:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su &quot;compromiso constante&quot; en la lucha contra la inmigraci\u00f3n irregular&quot;, y a los que ha garantizado el soporte espa\u00f1ol en el control\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#listItem\",\"name\":\"Grande-Marlaska destaca el \\u00abcar\\u00e1cter estrat\\u00e9gico\\u00bb de la relaci\\u00f3n bilateral con Senegal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#listItem\",\"position\":3,\"name\":\"Grande-Marlaska destaca el \\u00abcar\\u00e1cter estrat\\u00e9gico\\u00bb de la relaci\\u00f3n bilateral con Senegal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#newsarticle\",\"name\":\"Grande-Marlaska destaca el \\u00abcar\\u00e1cter estrat\\u00e9gico\\u00bb de la relaci\\u00f3n bilateral con Senegal | Cand\\u00e1s 365\",\"headline\":\"Grande-Marlaska destaca el \\u00abcar\\u00e1cter estrat\\u00e9gico\\u00bb de la relaci\\u00f3n bilateral con Senegal\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/300818-marlaska.jpg\",\"width\":496,\"height\":329},\"datePublished\":\"2018-08-31T18:06:45+02:00\",\"dateModified\":\"2018-08-31T18:06:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el agosto 31, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/\",\"name\":\"Grande-Marlaska destaca el \\u00abcar\\u00e1cter estrat\\u00e9gico\\u00bb de la relaci\\u00f3n bilateral con Senegal | Cand\\u00e1s 365\",\"description\":\"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\\u00fablica, Macky Sall, y con su hom\\u00f3logo senegal\\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su \\\"compromiso constante\\\" en la lucha contra la inmigraci\\u00f3n irregular\\\", y a los que ha garantizado el soporte espa\\u00f1ol en el control\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/300818-marlaska.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#mainImage\",\"width\":496,\"height\":329},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\\\/#mainImage\"},\"datePublished\":\"2018-08-31T18:06:45+02:00\",\"dateModified\":\"2018-08-31T18:06:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365","description":"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su \"compromiso constante\" en la lucha contra la inmigraci\u00f3n irregular\", y a los que ha garantizado el soporte espa\u00f1ol en el control","canonical_url":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#listItem","name":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#listItem","position":3,"name":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#newsarticle","name":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365","headline":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg","width":496,"height":329},"datePublished":"2018-08-31T18:06:45+02:00","dateModified":"2018-08-31T18:06:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el agosto 31, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#webpage","url":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/","name":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365","description":"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su \"compromiso constante\" en la lucha contra la inmigraci\u00f3n irregular\", y a los que ha garantizado el soporte espa\u00f1ol en el control","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg","@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#mainImage","width":496,"height":329},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/#mainImage"},"datePublished":"2018-08-31T18:06:45+02:00","dateModified":"2018-08-31T18:06:45+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365","og:description":"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su &quot;compromiso constante&quot; en la lucha contra la inmigraci\u00f3n irregular&quot;, y a los que ha garantizado el soporte espa\u00f1ol en el control","og:url":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg","og:image:width":496,"og:image:height":329,"article:published_time":"2018-08-31T18:06:45+00:00","article:modified_time":"2018-08-31T18:06:45+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal | Cand\u00e1s 365","twitter:description":"El ministro del Interior, Fernando Grande-Marlaska, se ha reunido en Dakar (Senegal) con el presidente de la Rep\u00fablica, Macky Sall, y con su hom\u00f3logo senegal\u00e9s, Aly Ngouille Ndiaye, a los que ha agradecido su &quot;compromiso constante&quot; en la lucha contra la inmigraci\u00f3n irregular&quot;, y a los que ha garantizado el soporte espa\u00f1ol en el control","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/08\/300818-marlaska.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"104126","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-21 23:01:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:46:05","updated":"2026-05-21 23:01:24","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tGrande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Grande-Marlaska destaca el \u00abcar\u00e1cter estrat\u00e9gico\u00bb de la relaci\u00f3n bilateral con Senegal","link":"https:\/\/candas365.es\/noticias\/grande-marlaska-destaca-el-caracter-estrategico-de-la-relacion-bilateral-con-senegal\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/104126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=104126"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/104126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/104127"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=104126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=104126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=104126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}