{"id":100395,"date":"2018-07-14T05:18:25","date_gmt":"2018-07-14T05:18:25","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=100395"},"modified":"2018-07-14T05:18:25","modified_gmt":"2018-07-14T05:18:25","slug":"infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/","title":{"rendered":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-99406\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-768x422.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-655x360.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-696x385.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720-764x420.jpg 764w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Mosc\u00fa, 13 jul (dpa) &#8211; A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar a Rusia 2018 como \u00abel mejor Mundial de la historia\u00bb.<\/p>\n<p>\u00abDesde hace un par de a\u00f1os pensaba que iba a ser el mejor, pero ahora lo puedo decir con convicci\u00f3n: es el mejor Mundial de la historia\u00bb, se\u00f1al\u00f3 el dirigente suizo en una rueda de prensa que brind\u00f3 a modo de balance del torneo en el estadio Luzhniki de Mosc\u00fa, la sede de la final del domingo.<\/p>\n<p>Infantino no se mostr\u00f3 muy abierto a conversar con medios internacionales durante el Mundial, pero hoy respondi\u00f3 preguntas a lo largo de m\u00e1s de una hora con su habitual locuacidad y sentido del humor.<\/p>\n<p>\u00ab\u00bfEres Bob Marley?\u00bb, interrumpi\u00f3 a un periodista de Etiop\u00eda que llam\u00f3 la atenci\u00f3n con sus rastas y el tradicional gorro del m\u00fasico jamaiquino. Infantino, euf\u00f3rico, ten\u00eda ganas de hablar. El suizo quiso gritar a los cuatro vientos que el Mundial de Rusia fue un \u00e9xito organizativo, que el VAR super\u00f3 su prueba de fuego y que el f\u00fatbol volvi\u00f3 a ocupar el centro de la escena tras a\u00f1os de esc\u00e1ndalos en la FIFA.<\/p>\n<p>\u00abEl f\u00fatbol fue el protagonista y por eso fue un \u00e9xito. Hemos devuelto el f\u00fatbol a la FIFA y hemos devuelto la FIFA al f\u00fatbol\u00bb, dijo Infantino, que lleg\u00f3 a la presidencia del organismo en febrero de 2016 despu\u00e9s del esc\u00e1ndalo de corrupci\u00f3n conocido como \u00abFIFAGate\u00bb.<\/p>\n<p>\u00abDejamos al f\u00fatbol que hablara. No se trata de que hablen los dirigentes, el presidente o los vicepresidentes. En un evento as\u00ed se trata de que hablen los jugadores\u00bb, agreg\u00f3.<\/p>\n<p>Infantino quiso agradecer especialmente al presidente Vladimir Putin y a Rusia por la organizaci\u00f3n y consider\u00f3 que el Mundial cambi\u00f3 la percepci\u00f3n y \u00ablas opiniones preconcebidas\u00bb que se tienen del pa\u00eds.<\/p>\n<p>\u00abEste Mundial ha cambiado la percepci\u00f3n del mundo sobre Rusia. Un mill\u00f3n de personas vinieron y han descubierto un pa\u00eds bonito, receptivo, muy rico en cultura, historia, en historia de la humanidad, historia de todos nosotros\u00bb, coment\u00f3. \u00abLas opiniones preconcebidas han cambiado gracias a esta Copa del Mundo. Se ha visto la naturaleza real de la gente aqu\u00ed en Rusia\u00bb.<\/p>\n<p>Infantino asegur\u00f3 adem\u00e1s que el f\u00fatbol ingres\u00f3 ya definitivamente en el ADN de los rusos. \u00abEste pa\u00eds ha cambiado. Se ha convertido en un pa\u00eds de f\u00fatbol, un pa\u00eds en el que el f\u00fatbol se ha convertido en parte del ADN, parte de la cultura. Gracias a la actuaci\u00f3n del seleccionado, pero tambi\u00e9n por la infraestructura y la organizaci\u00f3n\u00bb.<\/p>\n<p>INFANTINO APLAUDE EL VAR : \u00abLOS GOLES EN FUERA DE JUEGO HAN TERMINADO\u00bb<\/p>\n<p>El presidente de FIFA mostr\u00f3 adem\u00e1s su enorme satisfacci\u00f3n con la utilizaci\u00f3n del videoarbitraje en el Mundial de Rusia, el primer gran evento en el que se aplica el sistema.<\/p>\n<p>\u00abSi vas al diccionario y buscas la palabra progreso, pone &#8216;hacer las cosas mejor en comparaci\u00f3n con el pasado&#8217;. Eso es progreso, y el VAR es progreso para el f\u00fatbol\u00bb, indic\u00f3. \u00abEl VAR est\u00e1 limpiando el f\u00fatbol\u00bb, a\u00f1adi\u00f3 el dirigente suizo.<\/p>\n<p>\u00abEl gol en fuera de juego, por ejemplo, se ha terminado. No lo ver\u00e1n m\u00e1s, se ha terminado\u00bb, explic\u00f3 Infantino. \u00abAdem\u00e1s, cambia tambi\u00e9n la educaci\u00f3n. En este Mundial no ha habido ninguna roja por juego violento porque los jugadores saben que hay muchas c\u00e1maras y que les pueden expulsar\u00bb.<\/p>\n<p>Seg\u00fan datos de la FIFA, el VAR elev\u00f3 el porcentaje de acierto de los \u00e1rbitros de un 95 a un 99,32 por ciento. Hubo 19 revisiones hasta ahora en los 62 partidos, lo que equivale a una revisi\u00f3n cada tres partidos. \u00abDe esas 19 revisiones, en 16 casos se cambi\u00f3 la decisi\u00f3n del \u00e1rbitro. Esto quiere decir que pasamos de una decisi\u00f3n incorrecta a una correcta\u00bb, se\u00f1al\u00f3 Infantino.<\/p>\n<p>ELOGIOS A MESSI Y SILENCIO SUGESTIVO CON NEYMAR<\/p>\n<p>Infantino se mordi\u00f3 la lengua cuando le preguntaron por Neymar y su papel en el Mundial, donde el brasile\u00f1o fue m\u00e1s protagonista por sus exageraciones y simulaciones que por sus goles.<\/p>\n<p>\u00abNeymar es un gran jugador, eso lo primero, es un talento. No puedo decir nada negativo, es un futbolista tan talentoso&#8230; Neymar obviamente es uno de los &#8216;top&#8217;, por supuesto\u00bb, indic\u00f3 Infantino.<\/p>\n<p>\u00abY bueno, tambi\u00e9n&#8230;\u00bb, a\u00f1adi\u00f3 antes de quedarse callado, haciendo aspavientos y ri\u00e9ndose a carcajadas. \u00abMe gustar\u00eda ver m\u00e1s sus habilidades futbol\u00edsticas en el futuro. Estoy convencido de que le veremos jugar mejor en el futuro\u00bb.<\/p>\n<p>M\u00e1s contundente fue respecto del Mundial de Lionel Messi. \u00abMessi ha estado grand\u00edsimo, como siempre\u00bb, apunt\u00f3.<\/p>\n<p>\u00ab\u00bfSi pudo hacer m\u00e1s? Bueno, quiz\u00e1s si Argentina cuando ganaba 2-1 contra Francia se cerraba atr\u00e1s y segu\u00edan as\u00ed Messi pod\u00eda mostrar a\u00fan m\u00e1s sus calidades\u00bb, dijo Infantino sobre el encuentro que la albiceleste acab\u00f3 perdiendo 4-3. \u00ab(Pero) Messi no se puede discutir, es de los que nos hace so\u00f1ar desde hace diez a\u00f1os y va a seguir haci\u00e9ndonos so\u00f1ar\u00bb.<\/p>\n<p>\u00bfUN MUNDIAL DE 48 EQUIPOS EN QATAR 2022?<\/p>\n<p>Infantino se refiri\u00f3 por otra parte al Mundial de 2022 y no descart\u00f3 la posibilidad de que ya el torneo de Qatar se ampl\u00ede de 32 a 48 equipos, algo que est\u00e1 previsto en principio para 2026. \u00abDiscutiremos en los pr\u00f3ximos meses si hay una posibilidad. De momento lo que tenemos es una Copa de 32 equipos\u00bb, indic\u00f3.<\/p>\n<p>Tampoco cerr\u00f3 la puerta a extender el torneo a otros pa\u00edses del golfo, lo cual no parece del todo sencillo por la mala relaci\u00f3n de Qatar con varios de sus vecinos. \u00abSi todos piensan que es positivo cambiar algo, entonces podemos verlo. Todas las opciones est\u00e1n abiertas\u00bb.<\/p>\n<p>Por Tom\u00e1s Rudich (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mosc\u00fa, 13 jul (dpa) &#8211; A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar<\/p>\n","protected":false},"author":1,"featured_media":99406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-100395","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-14T05:18:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-07-14T05:18:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#listItem\",\"name\":\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#listItem\",\"position\":3,\"name\":\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#newsarticle\",\"name\":\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\\u00e1s 365\",\"headline\":\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/trophy-3472245_960_720.jpg\",\"width\":960,\"height\":528},\"datePublished\":\"2018-07-14T05:18:25+02:00\",\"dateModified\":\"2018-07-14T05:18:25+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el julio 14, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/\",\"name\":\"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\\u00e1s 365\",\"description\":\"Mosc\\u00fa, 13 jul (dpa) - A\\u00fan faltan dos d\\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\\u00f3 en proclamar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/trophy-3472245_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#mainImage\",\"width\":960,\"height\":528},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\\\/#mainImage\"},\"datePublished\":\"2018-07-14T05:18:25+02:00\",\"dateModified\":\"2018-07-14T05:18:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365","description":"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar","canonical_url":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#listItem","name":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#listItem","position":3,"name":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#newsarticle","name":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365","headline":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg","width":960,"height":528},"datePublished":"2018-07-14T05:18:25+02:00","dateModified":"2018-07-14T05:18:25+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el julio 14, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#webpage","url":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/","name":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365","description":"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#mainImage","width":960,"height":528},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/#mainImage"},"datePublished":"2018-07-14T05:18:25+02:00","dateModified":"2018-07-14T05:18:25+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365","og:description":"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar","og:url":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg","og:image:width":960,"og:image:height":528,"article:published_time":"2018-07-14T05:18:25+00:00","article:modified_time":"2018-07-14T05:18:25+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia | Cand\u00e1s 365","twitter:description":"Mosc\u00fa, 13 jul (dpa) - A\u00fan faltan dos d\u00edas para la final entre Francia y Croacia, pero Gianni Infantino celebr\u00f3 hoy como si hubiera levantado ya la copa. Vestido con el uniforme rojo que usan los voluntarios, con el pulgar hacia arriba y una enorme sonrisa, el presidente de la FIFA no dud\u00f3 en proclamar","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/trophy-3472245_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"100395","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 08:41:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:48:46","updated":"2025-08-27 08:41:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tInfantino proclama a Rusia 2018 como el mejor Mundial de la historia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Infantino proclama a Rusia 2018 como el mejor Mundial de la historia","link":"https:\/\/candas365.es\/noticias\/infantino-proclama-a-rusia-2018-como-el-mejor-mundial-de-la-historia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/100395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=100395"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/100395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/99406"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=100395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=100395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=100395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}